{"id":6939,"date":"2019-11-05T10:49:36","date_gmt":"2019-11-05T13:49:36","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=6939"},"modified":"2019-11-05T10:49:38","modified_gmt":"2019-11-05T13:49:38","slug":"fiscalia-y-pdi-desbaratan-red-de-trata-de-personas-que-explotaba-sexualmente-a-mujeres-colombianas-en-chile","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2019\/11\/05\/fiscalia-y-pdi-desbaratan-red-de-trata-de-personas-que-explotaba-sexualmente-a-mujeres-colombianas-en-chile\/","title":{"rendered":"Fiscal\u00eda y PDI desbaratan red de trata de personas que explotaba sexualmente a mujeres colombianas en Chile"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_6939\" class=\"pvc_stats total_only  \" data-element-id=\"6939\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>El operativo culmin\u00f3 con el rescate de 10 v\u00edctimas de nacionalidad colombiana que permanec\u00edan en situaci\u00f3n de explotaci\u00f3n sexual y la detenci\u00f3n de 8 personas identificadas como integrantes de la organizaci\u00f3n criminal.<\/p>\n\n\n\n<p>Una red internacional de trata de personas con fines de explotaci\u00f3n sexual que operaba en al menos 3 regiones del pa\u00eds fue desarticulada en diligencias simult\u00e1neas desarrolladas esta noche en Temuco, Puerto Montt, Osorno, Los \u00c1ngeles y Santiago, el marco de una indagatoria que lidera el fiscal jefe de Temuco Alberto Chiffelle.  <\/p>\n\n\n\n<p>Detectives de la Brigada Investigadora de Trata de Personas Metropolitana (Bitrap) de la PDI allanaron 9 domicilios y detuvieron a 8 integrantes de la organizaci\u00f3n criminal, 2 de ellos colombianos, en virtud de una orden judicial concedida por el Juzgado de Garant\u00eda de Temuco.<\/p>\n\n\n\n<p>El fiscal jefe de Temuco, Alberto Chiffelle, inform\u00f3 que en el operativo fueron rescatadas 10 v\u00edctimas, todas mujeres de nacionalidad colombiana, las cuales permanec\u00edan en situaci\u00f3n de explotaci\u00f3n sexual y viv\u00edan encerradas en habitaciones, monitoreadas permanentemente por c\u00e1maras de seguridad, en condiciones similares a la esclavitud.   \u201cNo una esclavitud como algunos se pueden imaginar con barrotes, privadas de libertad, sino una esclavitud moderna en el sentido de que eran v\u00edctimas de coacci\u00f3n.  Se aprovechaban de la vulnerabilidad de las mismas\u201d explic\u00f3 el persecutor.<\/p>\n\n\n\n<p>Chiffelle dijo que algunas de las mujeres reclutadas por esta red desconoc\u00edan que trabajar\u00edan en la prostituci\u00f3n. \u201cAlgunas ven\u00edan a ejercer  labores como trabajadora de casa particular, algunas de modelo. Y a otras derechamente se les indicaba que ven\u00edan a ejercer el comercio sexual, pero no en las condiciones que estaban ac\u00e1. Estamos hablando de condiciones de vida en donde deb\u00edan comer, alimentarse, trabajar en una misma pieza, privadas de comunicaciones, de sus tel\u00e9fonos, con imposibilidad de comunicarse con sus parientes \u201d.<\/p>\n\n\n\n<p>El jefe de la Bitrap, comisario Giordano Lanzarini, confirm\u00f3 que uno de los chilenos detenidos en Osorno ejerce como profesor  secundario y es sostenedor de un colegio. \u201c\u00c9l era uno de los integrantes de la asociaci\u00f3n il\u00edcita, de la red de trata de personas. Era uno de los financistas en este caso\u201d.<\/p>\n\n\n\n<p>La investigaci\u00f3n se inici\u00f3 en el mes de junio por la denuncia que realizaron 8 mujeres que escaparon de la organizaci\u00f3n criminal, la cual es -por la cantidad de v\u00edctimas y de regiones en las que operaba- la red de trata de personas con fines de explotaci\u00f3n sexual m\u00e1s grande desbaratada hasta ahora en Chile.   <\/p>\n\n\n\n<p>Los 8 imputados, quienes cumpl\u00edan distintos roles, ser\u00e1n presentados durante esta ma\u00f1ana de este martes en el tribunal de garant\u00eda de Temuco para la audiencia de formalizaci\u00f3n.  <\/p>\n\n\n\n<p><br> Las 10 mujeres rescatadas en los allanamientos, que se suman a otras 22 identificadas en la investigaci\u00f3n, fueron derivadas a la Unidad de Atenci\u00f3n a V\u00edctimas y Testigos de la Fiscal\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"455\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2019\/11\/TRata-de-personas2-1.jpg\" alt=\"\" class=\"wp-image-6942\" srcset=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2019\/11\/TRata-de-personas2-1.jpg 800w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2019\/11\/TRata-de-personas2-1-768x437.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6939\" class=\"pvc_stats total_only  \" data-element-id=\"6939\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El operativo culmin\u00f3 con el rescate de 10 v\u00edctimas de nacionalidad colombiana que permanec\u00edan en situaci\u00f3n de explotaci\u00f3n sexual y<\/p>\n","protected":false},"author":1,"featured_media":6941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[2021,133],"class_list":["post-6939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-araucania","tag-explotacion","tag-operativo"],"a3_pvc":{"activated":true,"total_views":93,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=6939"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6939\/revisions"}],"predecessor-version":[{"id":6943,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6939\/revisions\/6943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/6941"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=6939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=6939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=6939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}