{"id":6769,"date":"2019-10-22T20:35:00","date_gmt":"2019-10-22T23:35:00","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=6769"},"modified":"2019-10-22T20:35:02","modified_gmt":"2019-10-22T23:35:02","slug":"alcaldes-y-gobernador-de-malleco-se-reunen-para-evaluar-la-contingencia-en-la-provincia","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2019\/10\/22\/alcaldes-y-gobernador-de-malleco-se-reunen-para-evaluar-la-contingencia-en-la-provincia\/","title":{"rendered":"Alcaldes y Gobernador de Malleco se re\u00fanen para evaluar la contingencia en la provincia"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_6769\" class=\"pvc_stats total_only  \" data-element-id=\"6769\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<ul class=\"wp-block-list\"><li>La primera autoridad provincial unida con los alcaldes de la provincia de Malleco para enfrentar las distintas manifestaciones que se presentan en las comunas.<\/li><\/ul>\n\n\n\n<p>El Gobernador, V\u00edctor Manoli al ser consultado por el convulsionado ambiente social que vive el pa\u00eds, se\u00f1alo que \u201cClaramente comparto las leg\u00edtimas demandas que se han visualizado estos \u00faltimos d\u00edas en nuestro pa\u00eds, lo que no compartir\u00e9 jam\u00e1s son los hechos de violencia y desmanes ocurridos despu\u00e9s de estas marchan que se inician de forma pac\u00edfica y concluyen con desmanes\u201d enfatizo.<\/p>\n\n\n\n<p>La reuni\u00f3n se sostuvo en la sala de reuniones de la Gobernaci\u00f3n y cont\u00f3 con la presencia de los Alcaldes de las comunas de; Curacaut\u00edn, Victoria, Traigu\u00e9n, Pur\u00e9n, Los Sauces, Angol, Collipulli y Ercilla, adem\u00e1s de los representantes de los Alcaldes de Renaico y Lonquimay. Tambi\u00e9n estuvieron presentes las fuerzas policiales de Carabineros y PDI, quienes hicieron un balance de los da\u00f1os ocurridos despu\u00e9s de las manifestaciones.<\/p>\n\n\n\n<p>Por su parte los ediles al un\u00edsono rechazaron los hechos de violencia y vandalismo ocurridos en algunas comunas, se\u00f1alando que las demandas son ampliamente conocidas y validas pero que discrepan en la forma en que se han conducido las marchas, sobre todo en las comunas de Angol, donde locales comerciales sufrieron da\u00f1os en sus ventanales, robos de mercader\u00eda, ca\u00edda de sem\u00e1foro y dem\u00e1s da\u00f1os a la propiedad p\u00fablica y privada. Al ser consultado el alcalde, Enrique Neira este atendi\u00f3 el \u201cderecho a manifestarse por las distintas demandas sociales que aquejan a los ciudadanos pero que la violencia y hechos de vandalismo son ampliamente rechazados\u201d, comento.-<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6769\" class=\"pvc_stats total_only  \" data-element-id=\"6769\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La primera autoridad provincial unida con los alcaldes de la provincia de Malleco para enfrentar las distintas manifestaciones que se<\/p>\n","protected":false},"author":1,"featured_media":6770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[1993,510],"class_list":["post-6769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-araucania","tag-contingencia","tag-malleco"],"a3_pvc":{"activated":true,"total_views":27,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=6769"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6769\/revisions"}],"predecessor-version":[{"id":6771,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6769\/revisions\/6771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/6770"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=6769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=6769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=6769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}