{"id":6538,"date":"2019-10-11T16:56:20","date_gmt":"2019-10-11T19:56:20","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=6538"},"modified":"2019-10-11T16:56:22","modified_gmt":"2019-10-11T19:56:22","slug":"temuco-define-hoy-a-sus-finalistas-del-torneo-7x7-de-caja-los-andes%ef%bb%bf","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2019\/10\/11\/temuco-define-hoy-a-sus-finalistas-del-torneo-7x7-de-caja-los-andes%ef%bb%bf\/","title":{"rendered":"Temuco define hoy a sus finalistas del torneo 7&#215;7 de Caja Los Andes\ufeff"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_6538\" class=\"pvc_stats total_only  \" data-element-id=\"6538\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><br><\/p>\n\n\n\n<p>Entre los semifinalistas que se enfrentan hoy, se encuentra Casino Dreams versus Enjoy, mientras que en la otra llave chocar\u00e1n Icosen con Supermecado El Tr\u00e9bol. Los ganadores disputar\u00e1n la gran final que se juega el domingo 13 de octubre, donde el triunfador representar\u00e1 a la ciudad, en el regional contra los campeones de Concepci\u00f3n, Los \u00c1ngeles y Chill\u00e1n.\u00a0<\/p>\n\n\n\n<p>Cerca de las 19 horas, en las canchas del Complejo Santa Laura, se jugar\u00e1n las semifinales de la fase local del Torneo 7&#215;7 Caja Los Andes. La capital de la novena regi\u00f3n, recibir\u00e1 a los cuatro equipos ganadores de los cuartos de final, disputados ayer.&nbsp;<\/p>\n\n\n\n<p>En la primera jornada, Casino Dreams venci\u00f3 a Club de F\u00fatbol Rosen por 6-5, mientras que Icosen gole\u00f3 17-2 a Zacop, mientras en la segunda, Enjoy super\u00f3 por 6-3 a Matanza, y Supermecado El Tr\u00e9bol gan\u00f3 por 7-6 a FMDA FC en un apretado encuentro.<\/p>\n\n\n\n<p>Quien se corone campe\u00f3n hoy, esperar\u00e1 hasta el 19 de octubre, para enfrentar a los ganadores de Concepci\u00f3n, Los \u00c1ngeles y Chill\u00e1n. El ganador de esta zona, ir\u00e1 a Santiago para jugar el torneo nacional entre 21 y 23 de noviembre, que entrega como premio un viaje a Madrid. para todo el equipo, con todos los gastos pagados para visitar el Santiago Bernab\u00e9u.<\/p>\n\n\n\n<p>Uno de los jugadores de Enjoy, Enrique Flores, coment\u00f3 que esta es su segunda participaci\u00f3n en el torneo y que les gusta c\u00f3mo se llevan a cabo las fases: \u201cel campeonato est\u00e1 bien organizado, cuenta con todo con lo que uno necesita, hay buena disposici\u00f3n de los \u00e1rbitros, de las personas que llevan las planillas, se preocupan por tener kinesi\u00f3logos, un siete\u201d.<\/p>\n\n\n\n<p>En cuanto a los rivales, considera que: \u201chan sido parejos, hay que darlo todo, como si fuera una final cada partido, a Casino Dream, no lo hemos visto jugar, pero por lo que sabemos vienen bien preparados\u201d.<\/p>\n\n\n\n<p>Sobre el apoyo de la empresa, coment\u00f3 que \u00e9sta los apoy\u00f3 con todo: \u201cEn las camisetas, el lavado de estas, el transporte, las colaciones, la inscripci\u00f3n. Nosotros solo nos tenemos que preocupar de jugar\u201d, coment\u00f3.<\/p>\n\n\n\n<p>El torneo&nbsp;<strong>organizado por Caja Los Andes<\/strong>&nbsp;tiene como objetivo fomentar el deporte, la recreaci\u00f3n, la vida sana y la inclusi\u00f3n social de sus beneficiarios, a lo largo de todo Chile. Se trata del&nbsp;<strong>campeonato de futbolito m\u00e1s grande de Sudam\u00e9rica<\/strong>, en el que participar\u00e1n cerca de 800 empresas de todo Chile (incluye a equipos de damas y varones).<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6538\" class=\"pvc_stats total_only  \" data-element-id=\"6538\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Entre los semifinalistas que se enfrentan hoy, se encuentra Casino Dreams versus Enjoy, mientras que en la otra llave chocar\u00e1n<\/p>\n","protected":false},"author":1,"featured_media":6539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[101],"tags":[1966,1387],"class_list":["post-6538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-final","tag-futbol"],"a3_pvc":{"activated":true,"total_views":24,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=6538"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6538\/revisions"}],"predecessor-version":[{"id":6540,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/6538\/revisions\/6540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/6539"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=6538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=6538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=6538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}