{"id":64051,"date":"2026-07-14T21:42:21","date_gmt":"2026-07-15T00:42:21","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=64051"},"modified":"2026-07-14T21:42:21","modified_gmt":"2026-07-15T00:42:21","slug":"campana-solidaria-busca-recaudar-100-millones-de-pesos-para-salvar-la-vida-de-un-nino-puconino-que-padece-enfermedad-neurodegenerativa","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2026\/07\/14\/campana-solidaria-busca-recaudar-100-millones-de-pesos-para-salvar-la-vida-de-un-nino-puconino-que-padece-enfermedad-neurodegenerativa\/","title":{"rendered":"Campa\u00f1a solidaria busca recaudar 100 millones de pesos para salvar la vida de un ni\u00f1o puconino que padece enfermedad neurodegenerativa"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_64051\" class=\"pvc_stats total_only  \" data-element-id=\"64051\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p class=\"wp-block-paragraph\"><strong>Santiago Duarte Far\u00edas, de solo cinco a\u00f1os, fue aceptado en un ensayo cl\u00ednico en el extranjero que podr\u00eda frenar el avance de su enfermedad. Sin embargo, el tratamiento debe comenzar antes de que cumpla seis a\u00f1os. Hasta ahora, la familia ha reunido solo el 25% de la meta.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una verdadera carrera contra el tiempo vive la familia de&nbsp;<strong>Santiago Duarte Far\u00edas<\/strong>, un ni\u00f1o de cinco a\u00f1os de la comuna de Puc\u00f3n que enfrenta una compleja enfermedad neurodegenerativa progresiva denominada&nbsp;<strong>Leucodistrofia de Sustancia Blanca Evanescente (VWM)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo el lema&nbsp;<strong>&#8220;Todos por Santi&#8221;<\/strong>, sus padres iniciaron una campa\u00f1a solidaria para reunir&nbsp;<strong>100 millones de pesos<\/strong>, recursos que permitir\u00e1n costear su traslado y tratamiento en el extranjero, luego de ser aceptado en un ensayo cl\u00ednico que representa la \u00fanica alternativa para detener el avance de la enfermedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n es cr\u00edtica, ya que el protocolo m\u00e9dico establece que el tratamiento debe iniciarse antes de que Santiago cumpla seis a\u00f1os, edad que alcanzar\u00e1 el pr\u00f3ximo&nbsp;<strong>22 de diciembre<\/strong>. Esto deja a la familia con apenas cinco meses para conseguir la totalidad de los recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>No solo estamos pidiendo dinero, estamos pidiendo tiempo de vida para nuestro hijo. El ensayo cl\u00ednico en el extranjero es su \u00fanica y gran oportunidad, pero las puertas se cerrar\u00e1n definitivamente cuando cumpla los seis a\u00f1os. Necesitamos un milagro, estamos contra el tiempo<\/strong>&#8220;, expres\u00f3 con emoci\u00f3n&nbsp;<strong>Marla Far\u00edas<\/strong>, madre de Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta la fecha, la campa\u00f1a ha logrado recaudar cerca de&nbsp;<strong>26 millones de pesos<\/strong>, equivalente al&nbsp;<strong>25% de la meta<\/strong>, por lo que a\u00fan faltan alrededor de&nbsp;<strong>74 millones de pesos<\/strong>&nbsp;para concretar el tratamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia hizo un llamado a la solidaridad de personas, empresas e instituciones para ayudar a que Santiago pueda acceder a esta oportunidad que podr\u00eda cambiar su futuro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo colaborar?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes deseen aportar pueden realizar sus donaciones a las siguientes cuentas:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">BancoEstado<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Titular:<\/strong>\u00a0Marla Far\u00edas Leiva<\/li>\n\n\n\n<li><strong>RUT:<\/strong>\u00a017.716.057-1<\/li>\n\n\n\n<li><strong>Tipo de cuenta:<\/strong>\u00a0Cuenta Vista \/ Cuenta RUT<\/li>\n\n\n\n<li><strong>N.\u00ba de cuenta:<\/strong>\u00a017716057<\/li>\n\n\n\n<li><strong>Correo:<\/strong>\u00a0<a>marlafariasleiva@gmail.com<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Banco Tenpo<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Titular:<\/strong>\u00a0Marla Far\u00edas Leiva<\/li>\n\n\n\n<li><strong>RUT:<\/strong>\u00a017.716.057-1<\/li>\n\n\n\n<li><strong>Tipo de cuenta:<\/strong>\u00a0Cuenta Vista<\/li>\n\n\n\n<li><strong>N.\u00ba de cuenta:<\/strong>\u00a0111117716057<\/li>\n\n\n\n<li><strong>Correo:<\/strong>\u00a0<a>marlafariasleiva@gmail.com<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la campa\u00f1a mantiene activa su cuenta de Instagram&nbsp;<strong>@santiunguerrerovaliente<\/strong>, donde es posible encontrar informaci\u00f3n sobre el estado de Santiago y enlaces para realizar donaciones tanto desde Chile como desde el extranjero.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_64051\" class=\"pvc_stats total_only  \" data-element-id=\"64051\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Santiago Duarte Far\u00edas, de solo cinco a\u00f1os, fue aceptado en un ensayo cl\u00ednico en el extranjero que podr\u00eda frenar el<\/p>\n","protected":false},"author":1,"featured_media":64053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Santiago Duarte Far\u00edas, de 5 a\u00f1os, fue aceptado en un ensayo cl\u00ednico en el extranjero que podr\u00eda detener el avance de una rara enfermedad neurodegenerativa. Su familia necesita reunir $100 millones antes de diciembre para acceder al tratamiento y ya ha conseguido el 25% de la meta gracias a una campa\u00f1a solidaria.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14],"tags":[532],"class_list":["post-64051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temuco","tag-campana"],"a3_pvc":{"activated":true,"total_views":3725,"today_views":0},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2026\/07\/Campana.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/64051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=64051"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/64051\/revisions"}],"predecessor-version":[{"id":64054,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/64051\/revisions\/64054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/64053"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=64051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=64051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=64051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}