{"id":62310,"date":"2026-05-05T13:59:02","date_gmt":"2026-05-05T16:59:02","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=62310"},"modified":"2026-05-05T13:59:17","modified_gmt":"2026-05-05T16:59:17","slug":"inicia-ciclo-de-teatro-ciudadano-de-trashumantes","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2026\/05\/05\/inicia-ciclo-de-teatro-ciudadano-de-trashumantes\/","title":{"rendered":"Inicia ciclo de teatro ciudadano de Trashumantes"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_62310\" class=\"pvc_stats total_only  \" data-element-id=\"62310\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em>La cartelera incluye seis obras de compa\u00f1\u00edas y elencos regionales en el marco de la celebraci\u00f3n del D\u00eda Nacional del Teatro. Entradas disponibles en&nbsp;<a href=\"http:\/\/www.portaldisc.com\/\">www.portaldisc.com<\/a>.<\/em><\/p>\n\n\n\n<p>Este mes se llevar\u00e1 a cabo la primera versi\u00f3n del Ciclo de Teatro Ciudadano que organiza Trashumantes en el marco del D\u00eda Nacional del Teatro, que se celebra cada 11 de mayo en honor al natalicio del destacado director y actor Andr\u00e9s P\u00e9rez Araya (1951-2002), y que busca aportar a la construcci\u00f3n de tejido social y al ejercicio del derecho a la cultura.<\/p>\n\n\n\n<p>La cartelera incluye seis obras de compa\u00f1\u00edas y elencos ciudadanos de La Araucan\u00eda, que se presentar\u00e1n en Carpa Teatro Trashumantes (San Mart\u00edn 0891, Temuco) el 07, 08, 09, 14, 15 y 16 de mayo, a las 20:00 horas, para p\u00fablico desde los 14 a\u00f1os.&nbsp;<\/p>\n\n\n\n<p>\u201cGeneramos esta instancia para relevar el sentido p\u00fablico y comunitario de las artes esc\u00e9nicas y responde a nuestra convicci\u00f3n de que la cultura es un espacio de participaci\u00f3n activa para las comunidades\u201d, se\u00f1alan las directoras de Trashumantes, Andrea Richards y Gisela Buscaglione.&nbsp;<\/p>\n\n\n\n<p>La programaci\u00f3n, agregan las actrices, \u201cre\u00fane tanto a compa\u00f1\u00edas como a elencos ciudadanos, es decir, personas que no necesariamente provienen del \u00e1mbito profesional del teatro, pero que desarrollan procesos creativos desde sus propias experiencias, territorios e identidades\u201d.&nbsp;<\/p>\n\n\n\n<p>El ciclo contempla la presentaci\u00f3n de las obras: \u201cLas justas\u201d de Teatro Volc\u00e1nica, \u201cEl delantal blanco\u201d de Deskalabrateatro, \u201cEl retablillo de don Crist\u00f3bal\u201d de Kontrakultura Teatro, \u201cS\u00e9 feliz en el dolor\u201d de Colectivo Tr\u00e9mula, \u201cEcos que no mueren\u201d del Elenco Ciudadano Disidente y \u201cJacobo o la sumisi\u00f3n\u201d de Talleres de Teatro Temuco.&nbsp;<\/p>\n\n\n\n<p>Las entradas est\u00e1n disponibles en&nbsp;<a href=\"http:\/\/www.portaldisc.com\/evento\/ciclodeteatrociudadano\">www.portaldisc.com\/evento\/ciclodeteatrociudadano<\/a>&nbsp;en modalidad \u201cpaga lo que puedas\u201d desde $4.500.<\/p>\n\n\n\n<p><strong>CARTELERA LOCAL<\/strong><\/p>\n\n\n\n<p>Para inaugurar el ciclo, Teatro Volc\u00e1nica presentar\u00e1 \u201cLas justas\u201d el jueves 07 de mayo, una adaptaci\u00f3n contempor\u00e1nea de &#8220;Los justos&#8221; de Albert Camus que desplaza el conflicto original hacia un contexto actual marcado por la persistencia del poder patriarcal global.&nbsp;<\/p>\n\n\n\n<p>La acci\u00f3n se sit\u00faa en la inminente visita de un \u00edcono internacional del poder masculino \u2014religioso y pol\u00edtico\u2014 cuya figura representa estructuras hist\u00f3ricas de dominaci\u00f3n sobre los cuerpos y las vidas de las mujeres.<\/p>\n\n\n\n<p>El viernes 08 ser\u00e1 el turno de \u201cEl delantal blanco\u201d de Deskalabrateatro, una adaptaci\u00f3n de la obra del mismo nombre de Sergio Vodanovic, escrita en 1964 dentro de la trilog\u00eda \u201cVi\u00f1a: Tres comedias en traje de ba\u00f1o\u201d, las cuales est\u00e1n marcadas por el realismo, mostrando el conflicto de clases y la injusticia social de su \u00e9poca.&nbsp;<\/p>\n\n\n\n<p>Hoy, a m\u00e1s de 50 a\u00f1os, Deskalabrateatro la adapta para su montaje, como un acto de rescate de la memoria del teatro chileno, interpelando al p\u00fablico desde la comedia a cuestionar la asimetr\u00eda de las relaciones entre clases sociales y c\u00f3mo esta asimetr\u00eda es normalizada a pesar de la violencia que encierra.<\/p>\n\n\n\n<p>El s\u00e1bado 09, Kontrakultura Teatro presentar\u00e1 \u201cEl retablillo de don Crist\u00f3bal\u201d, obra escrita en farsa para t\u00edteres de Gui\u00f1ol. Su autor, el surrealista poeta y dramaturgo, Federico Garc\u00eda Lorca \u2014quien fuera asesinado por las tropas de Franco en su dictadura, por motivos de homofobia y fascismo, a mediados de los a\u00f1os 30 en Granada\u2014 presenta una obra en un lenguaje ir\u00f3nico \u0443 grotesco, haciendo una cr\u00edtica a los problemas sociales de su \u00e9poca.<\/p>\n\n\n\n<p>El jueves 14, Colectivo Tr\u00e9mula presentar\u00e1 \u201cS\u00e9 feliz en el dolor\u201d, obre que tiene como protagonista a Antonio, quien vive recluido en una diminuta habitaci\u00f3n intentando completar un plan que lleva siete a\u00f1os tejiendo en silencio.&nbsp;<\/p>\n\n\n\n<p>Su objetivo es el general Silva Renard, responsable de la masacre de la Escuela Santa Mar\u00eda de Iquique (1907), donde fue asesinado su hermano Manuel. En medio de su sed de venganza emergen fuerzas que lo devuelven a su humanidad y le recuerdan que existe vida m\u00e1s all\u00e1 del caos.&nbsp;<\/p>\n\n\n\n<p>El ciclo contin\u00faa el jueves 15 con \u201cEcos que no mueren\u201d del Elenco Ciudadano Disidente, obra que expone un mundo donde salir del cl\u00f3set sigue siendo una preocupaci\u00f3n para los adolescentes. Ah\u00ed, Nobi, su protagonista, encuentra una inesperada cercan\u00eda con su abuela, quien conecta con \u00e9l a trav\u00e9s de su propia historia de amor l\u00e9sbico. Distintas \u00e9pocas para una misma interrogante: \u00bfC\u00f3mo es vivir siendo disidente? Esta puesta en escena explora los conceptos de dignidad y voz, relacionando la biograf\u00eda de los integrantes del elenco con una ficci\u00f3n de amor marica.<\/p>\n\n\n\n<p>El ciclo finalizar\u00e1 el s\u00e1bado 16 con \u201cJacobo o la sumisi\u00f3n\u201d de Talleres de Teatro Temuco, obra fundamental del teatro del absurdo que satiriza ferozmente la obediencia familiar, el conservadurismo y la presi\u00f3n social. La trama sigue a un joven rebelde que se niega a cumplir con las normas sociales, hasta que su familia lo obliga a someterse y casarse con Roberta, una mujer con caracter\u00edsticas poco convencionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_62310\" class=\"pvc_stats total_only  \" data-element-id=\"62310\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La cartelera incluye seis obras de compa\u00f1\u00edas y elencos regionales en el marco de la celebraci\u00f3n del D\u00eda Nacional del<\/p>\n","protected":false},"author":1,"featured_media":62311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[86],"tags":[3883],"class_list":["post-62310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-panoramas","tag-transhumantes"],"a3_pvc":{"activated":true,"total_views":902,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/62310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=62310"}],"version-history":[{"count":2,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/62310\/revisions"}],"predecessor-version":[{"id":62313,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/62310\/revisions\/62313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/62311"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=62310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=62310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=62310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}