{"id":56053,"date":"2025-05-01T20:47:58","date_gmt":"2025-05-01T23:47:58","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=56053"},"modified":"2025-05-01T20:49:17","modified_gmt":"2025-05-01T23:49:17","slug":"sofo-valora-trabajo-de-la-comision-para-la-paz-y-el-entendimiento-pero-cuestiona-quiebre-en-principio-de-unanimidad","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2025\/05\/01\/sofo-valora-trabajo-de-la-comision-para-la-paz-y-el-entendimiento-pero-cuestiona-quiebre-en-principio-de-unanimidad\/","title":{"rendered":"SOFO valora trabajo de la Comisi\u00f3n para la Paz y el Entendimiento, pero cuestiona quiebre en principio de unanimidad"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_56053\" class=\"pvc_stats total_only  \" data-element-id=\"56053\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>La Sociedad de Fomento Agr\u00edcola de Temuco (SOFO) expres\u00f3 su reconocimiento al trabajo realizado por la Comisi\u00f3n para la Paz y el Entendimiento, especialmente destacando la participaci\u00f3n del representante del sector agr\u00edcola y de la Regi\u00f3n de La Araucan\u00eda, Sebasti\u00e1n Naveill\u00e1n.<\/p>\n\n\n\n<p>No obstante, la organizaci\u00f3n gremial manifest\u00f3 su preocupaci\u00f3n por lo que considera un quiebre en uno de los pilares fundamentales del proceso: el principio de unanimidad. \u201cLamentamos profundamente que no se haya respetado el principio de unanimidad como condici\u00f3n fundamental para la adopci\u00f3n de acuerdos, tal como fue establecido desde el inicio del proceso\u201d, se\u00f1alaron desde SOFO a trav\u00e9s de un comunicado.<\/p>\n\n\n\n<p>La comisi\u00f3n \u2014creada por el Gobierno con el objetivo de proponer soluciones estructurales al conflicto en la Macrozona Sur\u2014 ha desarrollado un trabajo con actores diversos del mundo pol\u00edtico, ind\u00edgena, agr\u00edcola y social. Sin embargo, las tensiones internas habr\u00edan derivado en propuestas sin el consenso de todos sus miembros, situaci\u00f3n que genera inquietud en el mundo agr\u00edcola.<\/p>\n\n\n\n<p>Desde SOFO anunciaron que analizar\u00e1n con detenci\u00f3n las propuestas una vez que sean difundidas oficialmente, y reiteraron su compromiso con el desarrollo integral de la zona. \u201cReafirmamos nuestra voluntad de seguir contribuyendo activamente a la seguridad, el bienestar y el desarrollo de todos quienes habitamos el sur de Chile, y de avanzar con decisi\u00f3n hacia una soluci\u00f3n real, concreta y duradera para la Macrozona Sur\u201d, concluyeron.<\/p>\n\n\n\n<p>El gremio agr\u00edcola ha sido un actor relevante en el debate sobre tierras, seguridad rural y desarrollo productivo en La Araucan\u00eda, y su opini\u00f3n respecto al proceso de la Comisi\u00f3n para la Paz ser\u00e1 clave en las pr\u00f3ximas semanas, cuando se den a conocer los detalles del informe final.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_56053\" class=\"pvc_stats total_only  \" data-element-id=\"56053\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La Sociedad de Fomento Agr\u00edcola de Temuco (SOFO) expres\u00f3 su reconocimiento al trabajo realizado por la Comisi\u00f3n para la Paz<\/p>\n","protected":false},"author":1,"featured_media":56054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[1224],"class_list":["post-56053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-comision"],"a3_pvc":{"activated":true,"total_views":3208,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/56053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=56053"}],"version-history":[{"count":2,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/56053\/revisions"}],"predecessor-version":[{"id":56056,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/56053\/revisions\/56056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/56054"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=56053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=56053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=56053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}