{"id":56050,"date":"2025-05-01T20:44:36","date_gmt":"2025-05-01T23:44:36","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=56050"},"modified":"2025-05-01T20:44:37","modified_gmt":"2025-05-01T23:44:37","slug":"uno-de-cada-tres-escolares-en-el-mundo-sufre-acoso-frecuente-experta-entrega-claves-para-enfrentar-esta-realidad","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2025\/05\/01\/uno-de-cada-tres-escolares-en-el-mundo-sufre-acoso-frecuente-experta-entrega-claves-para-enfrentar-esta-realidad\/","title":{"rendered":"Uno de cada tres escolares en el mundo sufre acoso frecuente: experta entrega claves para enfrentar esta realidad"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_56050\" class=\"pvc_stats total_only  \" data-element-id=\"56050\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em><strong>Detectar a tiempo las se\u00f1ales y actuar con empat\u00eda puede marcar la diferencia. Los adultos, dice la psic\u00f3loga de la UBO, cumplen un rol clave al observar cambios en el comportamiento de ni\u00f1as, ni\u00f1os y adolescentes y pueden brindar contenci\u00f3n antes de que el da\u00f1o emocional sea mayor.<\/strong><\/em><\/p>\n\n\n\n<p>El acoso escolar sigue siendo una de las principales amenazas a la convivencia y el bienestar emocional en las comunidades educativas. Aunque en muchos casos se disfraza de \u201cbromas\u201d o se minimiza como parte del desarrollo social, las cifras revelan una realidad alarmante. Solo en 2023 se reportaron m\u00e1s de 4.500 denuncias por&nbsp;<em>bullying<\/em>&nbsp;en establecimientos escolares del pa\u00eds, la segunda cifra m\u00e1s alta en los \u00faltimos diez a\u00f1os, seg\u00fan datos del Instituto Nacional de la Juventud (INJUV). M\u00e1s a\u00fan, el porcentaje de estudiantes que declara sufrir acoso de forma frecuente subi\u00f3 de un 11% en 2012 a un 19% en 2022.<\/p>\n\n\n\n<p>El fen\u00f3meno no es exclusivo de Chile. De acuerdo con cifras recientes de la UNESCO, uno de cada tres estudiantes a nivel mundial sufre acoso escolar cada mes. Adem\u00e1s, uno de cada diez ni\u00f1os es v\u00edctima de ciberacoso, una forma particularmente da\u00f1ina por su car\u00e1cter persistente y su alcance ilimitado, a lo que se suma la violencia f\u00edsica y simb\u00f3lica que afecta a millones de ni\u00f1os y adolescentes en edad escolar.<\/p>\n\n\n\n<p>\u201cEstamos frente a una forma de violencia sistem\u00e1tica que no siempre se ve, pero que deja huellas profundas. El acoso escolar no solo afecta el rendimiento acad\u00e9mico, sino que tambi\u00e9n perjudica la autoestima y la salud mental de quienes lo viven, adem\u00e1s de su familia y personas cercanas (ya sea desde el sufrimiento o desde el silencio que vive la v\u00edctima)\u201d, explica Viviana Tartakowsky, directora de la Escuela de Psicolog\u00eda de la Universidad Bernardo O\u2019Higgins (UBO).<\/p>\n\n\n\n<p>La especialista detalla que el hostigamiento puede tomar distintas formas: f\u00edsica, verbal, social, cibern\u00e9tica o incluso sexual. \u201cA veces ocurre porque alguien simplemente es distinto al resto debido a su origen, apariencia, su acento o por tener una necesidad especial. Lo grave es que muchas veces las v\u00edctimas no hablan ya sea por miedo, verg\u00fcenza o porque no encuentran un entorno seguro donde hacerlo\u201d, se\u00f1ala Tartakowsky a prop\u00f3sito del D\u00eda contra el Acoso Escolar que se conmemora este 2 de mayo.<\/p>\n\n\n\n<p>En este escenario, el rol de los adultos resulta clave. Estar atentos a se\u00f1ales como cambios de \u00e1nimo inexplicables, p\u00e9rdida de inter\u00e9s por asistir al colegio, lesiones sin causa clara o aislamiento social, puede marcar la diferencia. \u201cLos ni\u00f1os no siempre dicen con palabras lo que les pasa, pero su cuerpo y su comportamiento usualmente lo gritan. Es fundamental escuchar, acompa\u00f1ar y actuar\u201d, agrega la psic\u00f3loga.<\/p>\n\n\n\n<p>La experta, en este sentido, llama a intervenir si el ni\u00f1o o ni\u00f1a es quien ejerce el acoso. \u201cNo se trata de castigar sin m\u00e1s, sino de entender qu\u00e9 lo motiva a actuar as\u00ed, poner l\u00edmites firmes y ofrecer contenci\u00f3n y apoyo psicol\u00f3gico. Estas situaciones pueden ser una oportunidad para ense\u00f1ar empat\u00eda, responsabilidad y respeto por el otro\u201d, comenta Tartakowsky.<\/p>\n\n\n\n<p>Finalmente, la acad\u00e9mica universitaria recalca que combatir el&nbsp;<em>bullying<\/em>&nbsp;requiere m\u00e1s que fechas conmemorativas. A su juicio, se requiere una cultura escolar activa en la prevenci\u00f3n y sistemas de denuncia accesibles y eficaces. \u201cLa violencia no es parte del crecimiento. La convivencia y la resoluci\u00f3n pac\u00edfica de conflictos se aprende, y es tarea de todos ense\u00f1arla con palabras y hechos\u201d, afirma.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_56050\" class=\"pvc_stats total_only  \" data-element-id=\"56050\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Detectar a tiempo las se\u00f1ales y actuar con empat\u00eda puede marcar la diferencia. Los adultos, dice la psic\u00f3loga de la<\/p>\n","protected":false},"author":1,"featured_media":56051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[101],"tags":[599],"class_list":["post-56050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-escolares"],"a3_pvc":{"activated":true,"total_views":2197,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/56050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=56050"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/56050\/revisions"}],"predecessor-version":[{"id":56052,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/56050\/revisions\/56052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/56051"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=56050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=56050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=56050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}