{"id":55712,"date":"2025-03-31T10:42:44","date_gmt":"2025-03-31T13:42:44","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=55712"},"modified":"2025-03-31T10:42:45","modified_gmt":"2025-03-31T13:42:45","slug":"vino-rose-el-nuevo-himno-positivo-de-timo-inspirado-en-earth-wind-fire","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2025\/03\/31\/vino-rose-el-nuevo-himno-positivo-de-timo-inspirado-en-earth-wind-fire\/","title":{"rendered":"\u201cVino Ros\u00e9\u201d: el nuevo himno positivo de TIM\u00d8 inspirado en Earth, Wind &amp; Fire"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_55712\" class=\"pvc_stats total_only  \" data-element-id=\"55712\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p class=\"wp-block-paragraph\">Iniciando una nueva etapa para la banda colombiana nominada al Latin GRAMMY,&nbsp;<strong>TIM\u00d8<\/strong>nos emociona con su nueva canci\u00f3n con toques de m\u00fasica disco titulada \u201c&nbsp;<strong>Vino Ros\u00e9<\/strong>&nbsp;\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para su nuevo sencillo, la banda convoca la esencia de artistas como&nbsp;<em>Earth, Wind &amp; Fire<\/em>y tintes de bossa nova, exquisitamente mezcladas con una precisi\u00f3n de pop. \u201c&nbsp;<strong>Vino Ros\u00e9<\/strong>&nbsp;\u201d est\u00e1 disponible en todas las plataformas digitales a partir de hoy.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/V9t4xePmX5Y?si=Wrkn_vqvi8EumW8A\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Bailando entre brillantes cuerdas de guitarra y armon\u00edas de trompetas de estilo disco, la canci\u00f3n invita a los fans a sumergirse en un nuevo mundo para&nbsp;<strong>TIM\u00d8<\/strong>&nbsp;, reflejando los sonidos de la d\u00e9cada de los 2000, una \u00e9poca musical que ha sido fuente de inspiraci\u00f3n para la banda. Creada durante uno de sus viajes por carretera,&nbsp;<strong>Andr\u00e9s<\/strong>&nbsp;recuerda:&nbsp;<em>&#8220;Fue entonces cuando Alejo empez\u00f3 a tocar unos acordes inspirados en un grupo brasile\u00f1o llamado Naty Roots. Empezamos a improvisar una melod\u00eda s\u00f3lo por diversi\u00f3n ya cantar de forma parecida a como lo har\u00edan ellos en portugu\u00e9s, y as\u00ed surgi\u00f3 &#8216;Vino Ros\u00e9'&#8221;.<\/em>&nbsp;Este tema fue producido y compuesto por TIM\u00d8, junto a la colaboraci\u00f3n de Sebasti\u00e1n Avil\u00e9s, Mauricio Rengifo, Andr\u00e9s Torres y Nicol\u00e1s Galat.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><em>&#8220;Esta canci\u00f3n est\u00e1 inspirada en el estilo de grupos como Earth, Wind &amp; Fire, cuyas canciones transmitidas antiguas siempre fueron parte de nuestra infancia. Nos encanta la vibra que, porque es muy alegre, como cuando algo te sale bien de forma inesperada, sin haberlo planeado. Esa espontaneidad y energ\u00eda positiva son las que buscamos reflejar en la canci\u00f3n.&#8221;<\/em>&nbsp;<strong>\u2013 TIM \u00d8<\/strong><br>El estreno de \u201c&nbsp;<strong>Vino Ros\u00e9<\/strong>&nbsp;\u201d llega tras las dos nominaciones de TIM\u00d8 a los&nbsp;<strong>Premios Nuestra Tierra<\/strong>&nbsp;de este a\u00f1o. La banda fue reconocida en la categor\u00eda de \u201c&nbsp;<strong>Mejor D\u00fao o Grupo<\/strong>&nbsp;\u201d, as\u00ed como en la de \u201c&nbsp;<strong>Mejor Canci\u00f3n Pop<\/strong>&nbsp;\u201d por su \u00e9xito \u201c&nbsp;<strong>Luz<\/strong>&nbsp;\u201d.<br>\u201c&nbsp;<strong>Vino Ros\u00e9<\/strong>&nbsp;\u201d es el segundo lanzamiento de la banda en 2025, tras su reciente \u00e9xito de cumbia \u201c&nbsp;<strong>Diamante<\/strong>&nbsp;\u201d junto a&nbsp;<strong>Cardellino<\/strong>&nbsp;. Con un inicio de a\u00f1o prometedor y lleno de acci\u00f3n, TIM\u00d8 tambi\u00e9n celebra nuevas e innovadoras colaboraciones, como recientemente su colaboraci\u00f3n con&nbsp;<strong>Alex Ponce<\/strong>&nbsp;en el sencillo&nbsp;<strong>\u201cNo Volvere\u201d<\/strong>&nbsp;.<br><strong>TIM\u00d8<\/strong>&nbsp;se ha establecido r\u00e1pidamente como uno de los talentos del pop\/rock m\u00e1s prometedores de la m\u00fasica latina. Distinguidos por su estilo \u00fanico de difuminar las l\u00edneas entre g\u00e9neros, la aclamada banda colombiana busca ser un&nbsp;<em>amigo<\/em>&nbsp;para cada uno de sus oyentes, creando canciones que resuenan profundamente con sus fans a trav\u00e9s de experiencias universales compartidas.&nbsp;<strong>\u201cVino Ros\u00e9\u201d<\/strong>&nbsp;sin duda es otra canci\u00f3n que se sumar\u00e1 a la lista de las favoritas de los fans de TIM\u00d8.\u00a1Escuchala en tus plataformas favoritas!<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_55712\" class=\"pvc_stats total_only  \" data-element-id=\"55712\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Iniciando una nueva etapa para la banda colombiana nominada al Latin GRAMMY,&nbsp;TIM\u00d8nos emociona con su nueva canci\u00f3n con toques de<\/p>\n","protected":false},"author":1,"featured_media":55713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[369],"tags":[3283],"class_list":["post-55712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-himno"],"a3_pvc":{"activated":true,"total_views":2254,"today_views":0},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/03\/unnamed-2.png","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=55712"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55712\/revisions"}],"predecessor-version":[{"id":55714,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55712\/revisions\/55714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/55713"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=55712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=55712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=55712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}