{"id":55698,"date":"2025-03-30T15:50:56","date_gmt":"2025-03-30T18:50:56","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=55698"},"modified":"2025-03-30T15:50:57","modified_gmt":"2025-03-30T18:50:57","slug":"matthei-lidera-la-primera-medicion-presidencial-del-ano-de-data-influye-toha-aparece-en-tercer-lugar","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2025\/03\/30\/matthei-lidera-la-primera-medicion-presidencial-del-ano-de-data-influye-toha-aparece-en-tercer-lugar\/","title":{"rendered":"Matthei lidera la primera medici\u00f3n presidencial del a\u00f1o de Data Influye, Toh\u00e1 aparece en tercer lugar"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_55698\" class=\"pvc_stats total_only  \" data-element-id=\"55698\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p class=\"wp-block-paragraph\"><em>En una consulta espont\u00e1nea la candidata de Chile Vamos aparece con un 22% de las preferencias seguida por Johannes Kaiser con un 15% y Carolina Toh\u00e1, quien anunci\u00f3 su candidatura hace tres semanas, con un 12%. Pese a esto, el sondeo arroj\u00f3 tambi\u00e9n que el 66% de los encuestados no est\u00e1 conforme y no encuentra un candidato que represente sus ideas.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Santiago, 26 de marzo de 2025.<\/strong>&nbsp;La encuesta Data Influye de marzo de 2025, elaborada por la consultora de opini\u00f3n p\u00fablica T\u00fa Influyes, realiz\u00f3 la primera medici\u00f3n espont\u00e1nea del a\u00f1o sobre preferencias presidenciales, en un contexto marcado por la renuncia de autoridades del gabinete y la preparaci\u00f3n de las primarias legales organizadas por el Servel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frente a la pregunta abierta sobre qui\u00e9n le gustar\u00eda que fuera el pr\u00f3ximo presidente o presidenta de Chile, Evelyn Matthei lidera con un 22%, seguida por Johannes Kaiser con 15%, Carolina Toh\u00e1 Toh\u00e1 con 12%, Jos\u00e9 Antonio Kast con 8% y Michelle Bachelet con 5%.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de la amplitud de nombres, un 66% de los encuestados declara no estar conforme con la oferta actual de candidaturas y que faltan candidatos que representen mejores sus ideas, mientras que un 6% probablemente anular\u00e1 su voto o no votar\u00e1. De hecho, el sondeo arroj\u00f3 tambi\u00e9n que un 45% indica que no participar\u00e1 en ninguna primaria, mientras que un 30% lo har\u00eda en la primaria de Chile Vamos, donde figuran Matthei y Rinc\u00f3n, y un 25% en la primaria oficialista, que incluye a Toh\u00e1, Jara y Winter, entre otros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pol\u00edtica internacional y nuevo orden global<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frente al contexto internacional, marcado por la posible reelecci\u00f3n de Donald Trump en Estados Unidos, los encuestados visualizan a China como la potencia m\u00e1s influyente en el futuro, con un 49%, seguida por Estados Unidos con un 31%. Consultados por la alianza m\u00e1s conveniente para Chile, un 31% opta por China, un 31% por Estados Unidos y un 22% por la Uni\u00f3n Europea.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 45% estima que Chile deber\u00eda diversificar sus relaciones internacionales sin depender de una sola potencia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Seguridad p\u00fablica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a los temas que podr\u00edan debilitar al Gobierno, la delincuencia y violencia criminal lideran con un 42%, esto es 5 puntos m\u00e1s que en el sondeo de enero, seguida de la percepci\u00f3n de casos de corrupci\u00f3n (16%).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el uso de pistolas Taser no letales por parte de los guardias municipales, un 39% est\u00e1 de acuerdo sin condiciones y un 44% lo aprueba bajo supervisi\u00f3n y capacitaci\u00f3n estricta. Solo un 15% opina que el uso de armas debe ser exclusivo de Carabineros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Evaluaci\u00f3n pol\u00edtica y ministros<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gesti\u00f3n del presidente Gabriel Boric tiene un 33% de aprobaci\u00f3n y un 58% (+3) de desaprobaci\u00f3n, mientras que el gobierno en general obtiene un 34% de aprobaci\u00f3n y un 54% de desaprobaci\u00f3n. La oposici\u00f3n es evaluada con un 71% de desaprobaci\u00f3n y un 9% de aprobaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la evaluaci\u00f3n del gabinete, Jaime Pizarro se mantiene como el ministro mejor evaluado entre quienes lo conocen, con un 55% de aprobaci\u00f3n. Le siguen Mario Marcel (50%) y Jeanette Jara que aument\u00f3 3 puntos respecto a enero y qued\u00f3 con 46%. En el grupo con menor evaluaci\u00f3n se encuentran el titular de Econom\u00eda, Nicol\u00e1s Grau (31%), Antonia Orellana, ministra de la Mujer y la Equidad de G\u00e9nero (30%) y el ministro de Energ\u00eda, Diego Pardow (27%).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la consulta sobre cu\u00e1l de los referentes pol\u00edticos siente que lo representa, un 39% de las personas sondeadas respondi\u00f3 que ninguna, seguida por el Frente Amplio con un 11%, Socialismo Democr\u00e1tico (PPD, PS, PR Liberales) con un 10% y el PC con un 5%. Mientras que Republicanos, Chile Vamos y el Partido Nacional Libertario, este \u00faltimo legalizado a comienzos de marzo de este a\u00f1o, cuentan con un 9% cada uno.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00e1mbito econ\u00f3mico, la encuesta Data Influye de marzo muestra que un 39% de los encuestados califica su situaci\u00f3n econ\u00f3mica actual como \u201cmuy mala\u201d o \u201cmala\u201d, mientras que un 42% la considera \u201cni buena ni mala\u201d. En cambio, un 20% se\u00f1ala que su situaci\u00f3n es \u201cbuena\u201d o \u201cmuy buena\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto a las expectativas sobre la recuperaci\u00f3n econ\u00f3mica del pa\u00eds, un 49% (-6) cree que tomar\u00e1 m\u00e1s de dos a\u00f1os, un 24% estima que ocurrir\u00e1 entre uno y dos a\u00f1os, y un 13% (+5) proyecta que el proceso se completar\u00e1 en seis meses. Consultados por el desempe\u00f1o de la econom\u00eda en 2025, un 39% considera que se progresar\u00e1, un 37% cree que estacar\u00e1 y un 23% estima que decaer\u00e1.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La encuesta fue realizada entre el 18 y el 21 de marzo de 2025, con una muestra de 1.022 casos representativos a nivel nacional. El margen de error no probabil\u00edstico es del 3% y el nivel de confianza del 95%. Para m\u00e1s informaci\u00f3n, visita&nbsp;<a href=\"https:\/\/tuinfluyes.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tuinfluyes.com<\/a>&nbsp;o escribe a&nbsp;<a href=\"mailto:info@tuinfluyes.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@tuinfluyes.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_55698\" class=\"pvc_stats total_only  \" data-element-id=\"55698\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>En una consulta espont\u00e1nea la candidata de Chile Vamos aparece con un 22% de las preferencias seguida por Johannes Kaiser<\/p>\n","protected":false},"author":1,"featured_media":54678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[84],"tags":[3577],"class_list":["post-55698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-elecciones"],"a3_pvc":{"activated":true,"total_views":2223,"today_views":0},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/01\/Apoyo-Matthei-scaled.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=55698"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55698\/revisions"}],"predecessor-version":[{"id":55699,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55698\/revisions\/55699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/54678"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=55698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=55698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=55698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}