{"id":55223,"date":"2025-02-24T09:07:27","date_gmt":"2025-02-24T12:07:27","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=55223"},"modified":"2025-02-24T09:07:28","modified_gmt":"2025-02-24T12:07:28","slug":"agricultores-afectados-por-incendios-en-la-araucania-reciben-ayuda-del-mercado-lo-valledor","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2025\/02\/24\/agricultores-afectados-por-incendios-en-la-araucania-reciben-ayuda-del-mercado-lo-valledor\/","title":{"rendered":"Agricultores afectados por incendios en La Araucan\u00eda reciben ayuda del Mercado Lo Valledor"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_55223\" class=\"pvc_stats total_only  \" data-element-id=\"55223\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em>Se entregaron bebidas isot\u00f3nicas, agua, leche y alimentos no perecibles, a bomberos, brigadistas y las personas perjudicadas por los siniestros. Adem\u00e1s, 15 toneladas de alimentos hortofrut\u00edcola org\u00e1nico para los animales, fueron trasladados hasta la provincia de Malleco para apoyar a las familias campesinas damnificadas.<\/em><\/p>\n\n\n\n<p>El Mercado Mayorista Lo Valledor, junto a consorcio Santa Marta y la Fundaci\u00f3n REALIM, entreg\u00f3 un aporte para los damnificados por los incendios en la provincia de Malleco en La Araucan\u00eda.<\/p>\n\n\n\n<p>La donaci\u00f3n contempl\u00f3 alimentos no perecibles, bebidas isot\u00f3nicas, leche y conservas, entre otros, para los damnificados, bomberos y personal de CONAF. Tambi\u00e9n, se trasladaron 15 toneladas de productos vegetales y org\u00e1nicos, destinado al consumo de los animales de las familias campesinas y agricultoras.<\/p>\n\n\n\n<p>\u201cHay un tremendo aporte desde el mercado Lo Valledor con el consorcio Santa Marta y la fundaci\u00f3n REALIM. Hicieron una campa\u00f1a que permiti\u00f3 entregar aguas, bebidas isot\u00f3nicas, tanto a bomberos como a personal de CONAF\u201d, destac\u00f3 el seremi de Agricultura, H\u00e9ctor Cumilaf. &nbsp;<\/p>\n\n\n\n<p>La ayuda otorgada por Mercado Lo Valledor, Fundaci\u00f3n REALIM y Consorcio Santa Marta, tuvo como destino a m\u00e1s de 120 productores agr\u00edcolas de sectores rurales de la comuna de Pur\u00e9n. El operativo fue organizando por autoridades como el ministro de Agricultura, Esteban Valenzuela, el administrador general de Lo Valledor, Gonzalo Bravo, y representantes de las empresas aportantes y colaboradoras. En el aporte, tambi\u00e9n participaron las empresas Dimarc, Comercial Castro y Hervas.<\/p>\n\n\n\n<p><strong>Apoyo a Agricultores<\/strong><\/p>\n\n\n\n<p>Uno de los sectores afectados por los incendios forestales, en Pur\u00e9n, fue la localidad de Huitranlebu, donde viven 120 familias y que tuvo un da\u00f1o de ocho casas y la afectaci\u00f3n a un sistema de Agua Potable Rural (APR) que result\u00f3 con p\u00e9rdida total.<\/p>\n\n\n\n<p>El comandante de bomberos de la localidad, Alexis Guti\u00e9rrez, declar\u00f3 que \u201ceste a\u00f1o ha sido un verano intenso en Pur\u00e9n. Hemos tenido una cantidad muy significativa de incendios forestales, m\u00e1s altos que lo que tuvimos en temporadas anteriores\u201d. El comandante afirm\u00f3 que las ayudas, como las que entreg\u00f3 Lo Valledor en conjunto con REALIM y Santa Marta, les da fuerza para contener los incendios: \u201cAyuda bastante a nuestra log\u00edstica y a nuestros recursos que disponemos. Esto nos ayuda bastante para seguir trabajando con la emergencia\u201d.<\/p>\n\n\n\n<p>El alcalde de Pur\u00e9n, Frann Barbieri, explic\u00f3 que son importantes todos los aportes y el trabajo en conjunto del sector p\u00fablico y privado para la agricultura que se vio afectada en la regi\u00f3n. \u201cTenemos que apoyar a toda esta gente con alimentos para ellos y para sus animales. Hay que recordar que se perdieron casas y viviendas, al igual que se perdi\u00f3 mucho predio, y eso significa que los animales no tienen donde comer. Por lo tanto, toda la ayuda que nos est\u00e1 llegando es bien recibida y se agradece mucho\u201d, coment\u00f3 Barbieri durante la donaci\u00f3n del Mercado Lo Valledor.<\/p>\n\n\n\n<p>Por su parte, el jefe provincial de CONAF en Malleco, Jorge Salvo, afirm\u00f3 que las ayudas que realizan entidades como Lo Valledor, son un aporte en que \u201cse visualicen los problemas que tenemos, siendo esta una buena forma para sentirnos acompa\u00f1ados, ya que vemos que est\u00e1n preocupadas por una comuna tan importante para nosotros, como es Pur\u00e9n\u201d. Salvo destac\u00f3 que la labor por detener los incendios es muy complicada: \u201cHa sido un trabajo intenso, tanto de bomberos, CONAF y todos los equipos de emergencia, por tanto, la ayuda que nos pueden brindar, en este caso como el mercado Lo Valledor, es muy significativo como para una comuna como Pur\u00e9n\u201d.<\/p>\n\n\n\n<p>El operativo de ayuda, comenz\u00f3 a principios de semana cuando el ministro de Agricultura, Esteban Valenzuela, se traslad\u00f3 al Mercado Lo Valledor, all\u00ed se reuni\u00f3 con el administrador general de este centro de distribuci\u00f3n, Gonzalo Bravo; al presidente de la fundaci\u00f3n REALIM, Crist\u00f3bal Meri\u00f1o y al gerente general del Consorcio Santa Marta, Alberto Tagle.<\/p>\n\n\n\n<p>Las instituciones nombradas articularon una campa\u00f1a para traer desde Santiago a la comuna de Pur\u00e9n, 25 toneladas de ayuda que consisten en 10 toneladas de alimentos para afectados y 15 toneladas de alimentaci\u00f3n animal, para beneficiar a 500 crianceros de La Araucan\u00eda, aproximadamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/02\/lo-valledor-en-Puren-006-1000x666.jpg\" alt=\"\" class=\"wp-image-55225\" srcset=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/02\/lo-valledor-en-Puren-006-1000x666.jpg 1000w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/02\/lo-valledor-en-Puren-006-768x512.jpg 768w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/02\/lo-valledor-en-Puren-006-1536x1023.jpg 1536w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2025\/02\/lo-valledor-en-Puren-006.jpg 1600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_55223\" class=\"pvc_stats total_only  \" data-element-id=\"55223\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Se entregaron bebidas isot\u00f3nicas, agua, leche y alimentos no perecibles, a bomberos, brigadistas y las personas perjudicadas por los siniestros.<\/p>\n","protected":false},"author":1,"featured_media":55224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[479],"class_list":["post-55223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temuco","tag-agricultores"],"a3_pvc":{"activated":true,"total_views":1494,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=55223"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55223\/revisions"}],"predecessor-version":[{"id":55226,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/55223\/revisions\/55226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/55224"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=55223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=55223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=55223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}