{"id":51844,"date":"2024-08-08T09:30:40","date_gmt":"2024-08-08T12:30:40","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=51844"},"modified":"2024-08-08T09:30:41","modified_gmt":"2024-08-08T12:30:41","slug":"diputado-leal-presenta-denuncia-en-la-sec-e-impulsa-comision-investigadora-tras-extensos-cortes-de-luz-que-afectan-a-mas-de-60-mil-hogares-en-la-araucania","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2024\/08\/08\/diputado-leal-presenta-denuncia-en-la-sec-e-impulsa-comision-investigadora-tras-extensos-cortes-de-luz-que-afectan-a-mas-de-60-mil-hogares-en-la-araucania\/","title":{"rendered":"Diputado Leal presenta denuncia en la SEC e impulsa comisi\u00f3n investigadora tras\u00a0extensos cortes de luz que afectan a m\u00e1s de 60 mil hogares en La Araucan\u00eda"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_51844\" class=\"pvc_stats total_only  \" data-element-id=\"51844\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em>El parlamentario de la UDI calific\u00f3 como \u201cinjustificable\u201d la interrupci\u00f3n del servicio en la regi\u00f3n, lo que incluso oblig\u00f3<\/em><em>&nbsp;<\/em><em>a<\/em><em>&nbsp;que ocho comunas tuvieran que suspender las clases este lunes.<\/em><\/p>\n\n\n\n<p>El diputado por el Distrito 23 e integrante de la comisi\u00f3n de Seguridad Ciudadana, Henry Leal (UDI), present\u00f3 este lunes una denuncia ante la Superintendencia de Electricidad y Combustibles (SEC), luego que durante esta ma\u00f1ana las autoridades reportaran que a\u00fan exist\u00edan 61.691 hogares con el suministro el\u00e9ctrico interrumpido en La Araucan\u00eda, pese a que han pasado m\u00e1s de 72 horas desde el intenso temporal que afect\u00f3 a la zona, con r\u00e1fagas de viento que incluso superaron los 100 km\/h.<\/p>\n\n\n\n<p>Al respecto, el parlamentario gremialista calific\u00f3 como \u201cabsolutamente inaceptable e injustificable\u201d la demora en la reposici\u00f3n del servicio, lo que este lunes llev\u00f3 incluso a que ocho comunas de la regi\u00f3n tuvieran que suspender las clases en los establecimientos debido a los cortes de luz.<\/p>\n\n\n\n<p>Por lo mismo, el diputado Leal -junto al resto de los integrantes de la Bancada UDI- presentaron esta ma\u00f1ana una denuncia formal ante la SEC, solicitando iniciar un procedimiento en contra de las compa\u00f1\u00edas el\u00e9ctricas ante los masivos y extensos cortes que se registraron, de manera de poder determinar distintas compensaciones e indemnizaciones para quienes m\u00e1s se han visto afectados.<\/p>\n\n\n\n<p>\u201cLo que est\u00e1 ocurriendo en nuestra regi\u00f3n y en gran parte del pa\u00eds es absolutamente inaceptable e injustificable. Ning\u00fan sistema frontal, por m\u00e1s intenso que haya sido, deber\u00eda causar este nivel de estragos en el territorio. Ya llevamos m\u00e1s de 72 horas desde el temporal y a\u00fan existen m\u00e1s de 60 mil hogares con el servicio interrumpido en La Araucan\u00eda. Y no s\u00f3lo estamos hablando de familias con ni\u00f1os o adultos mayores, sino que tambi\u00e9n de hogares con pacientes electrodependientes, comit\u00e9s de Agua Potable Rural (APR), emprendedores y muchos locales comerciales, que suelen perder toda su mercader\u00eda y electrodom\u00e9sticos, sin que nadie les responda\u201d, cuestion\u00f3 el parlamentario UDI.<\/p>\n\n\n\n<p>Pero adem\u00e1s de la denuncia que present\u00f3 esta ma\u00f1ana, el representante de La Araucan\u00eda tambi\u00e9n anunci\u00f3 que durante la jornada de hoy impulsar\u00e1 una comisi\u00f3n investigadora en la C\u00e1mara de Diputados, donde no s\u00f3lo buscar\u00e1 citar a las compa\u00f1\u00edas responsables, sino que tambi\u00e9n a las autoridades del Ministerio de Energ\u00eda, la SEC y la Comisi\u00f3n Nacional de Energ\u00eda (CNE), entre otras.<\/p>\n\n\n\n<p>Lo&nbsp;anterior,&nbsp;con&nbsp;el&nbsp;objetivo&nbsp;de&nbsp;determinar&nbsp;las&nbsp;responsabilidades&nbsp;en&nbsp;la&nbsp;actual&nbsp;crisis,&nbsp;como&nbsp;tambi\u00e9n&nbsp;para evaluar otras acciones que se deban adoptar a fin de evitar que vuelva a ocurrir la misma situaci\u00f3n.<\/p>\n\n\n\n<p>\u201cVamos a ejercer todas las acciones que tengamos a nuestro alcance, tanto judiciales como pol\u00edticas, para que se determinen todas las responsabilidades que existan y se compense de manera efectiva a las miles de personas que se han visto afectadas. Ya basta de que las compa\u00f1\u00edas el\u00e9ctricas y las propias autoridades se sigan lavando las manos, porque todos los a\u00f1os se repite la misma historia y jam\u00e1s hemos visto, por ahora, que adopten alguna medida al respecto\u201d, reiter\u00f3 el diputado Leal.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_51844\" class=\"pvc_stats total_only  \" data-element-id=\"51844\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El parlamentario de la UDI calific\u00f3 como \u201cinjustificable\u201d la interrupci\u00f3n del servicio en la regi\u00f3n, lo que incluso oblig\u00f3&nbsp;a&nbsp;que ocho<\/p>\n","protected":false},"author":1,"featured_media":40616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[154],"class_list":["post-51844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-diputado"],"a3_pvc":{"activated":true,"total_views":1016,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/51844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=51844"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/51844\/revisions"}],"predecessor-version":[{"id":51845,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/51844\/revisions\/51845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/40616"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=51844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=51844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=51844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}