{"id":47508,"date":"2024-01-23T08:53:55","date_gmt":"2024-01-23T11:53:55","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=47508"},"modified":"2024-01-23T08:53:56","modified_gmt":"2024-01-23T11:53:56","slug":"fundacion-araucaniaprende-marca-un-precedente-apoyando-aprendizajes-de-nins-de-atacama","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2024\/01\/23\/fundacion-araucaniaprende-marca-un-precedente-apoyando-aprendizajes-de-nins-de-atacama\/","title":{"rendered":"Fundacion Araucan\u00edaPrende marca un precedente apoyando aprendizajes de ni\u00f1@s de Atacama"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_47508\" class=\"pvc_stats total_only  \" data-element-id=\"47508\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>Porque no importa en qu\u00e9 regi\u00f3n vivan los ni\u00f1os que requieren aprender en igualdad de condiciones, Araucan\u00edAprende junto a 2 fundaciones se movilizaron para poner a disposici\u00f3n de ni\u00f1os de las comunas de Copiap\u00f3 y Tierra Amarilla, una alternativa v\u00e1lida de aprendizaje a distancia.<\/p>\n\n\n\n<p>Durante meses m\u00e1s de 30 mil alumnos de Atacama, matriculados en establecimientos educacionales dependientes del Servicio Local de Educaci\u00f3n P\u00fablica de las comunas de Copiap\u00f3, Tierra Amarilla, Caldera, Cha\u00f1aral y Diego de Almagro, permanecieron sin clases. Ante este preocupante escenario educativo, Fundaci\u00f3n Araucan\u00edAprende moviliz\u00f3 a su equipo para contribuir a ni\u00f1os y sus familias en el camino de la nivelaci\u00f3n y recuperaci\u00f3n de aprendizajes.<\/p>\n\n\n\n<p>Para brindar apoyo efectivo en la regi\u00f3n de Atacama, el contacto se realiz\u00f3 de manera directa con las familias a trav\u00e9s de \u201cEscuelas Abiertas\u201d, organizaci\u00f3n a la que en una visita en terreno padres y madres manifestaron preocupaci\u00f3n por la falta de clases de sus hijos e inter\u00e9s por participar de acciones que les permitieran salir del rezago.<\/p>\n\n\n\n<p>Trabajo colaborativo<\/p>\n\n\n\n<p>Con las alarmas encendidas Araucan\u00edAprende se comprometi\u00f3 con los ni\u00f1os de Atacama, as\u00ed lo explic\u00f3 Tatiana \u00c1lvarez, Coordinadora del Rescate Lector y de las Tutor\u00edas de Atacama de Fundaci\u00f3n Araucan\u00edAprende, \u201cen la reuni\u00f3n en la que invitamos a las familias a participar de esta iniciativa, sus mayores preocupaciones eran los retrocesos en los aprendizajes de sus hijos, en su mayor\u00eda ni\u00f1os de 1\u00b0 y 2\u00b0 b\u00e1sico que se estaban iniciando en el aprendizaje de la lectura, dentro de los que tambi\u00e9n figuran ni\u00f1os con necesidades educativas especiales, que no hab\u00edan recibiendo las intervenciones de profesionales del equipo PIE. Nos encontramos con familias que lo \u00fanico que desean es poder nivelar los aprendizajes de sus hijos y contar con orientaci\u00f3n para afrontar el a\u00f1o acad\u00e9mico 2024\u201d.<\/p>\n\n\n\n<p>De esta forma Araucan\u00edAprende junto a las fundaciones Mar\u00eda Jos\u00e9 Reyes Moore (regi\u00f3n del B\u00edo B\u00edo) y Letra Libre (regi\u00f3n Metropolitana)-que tambi\u00e9n integran de la Red Por un Chile que Lee-desde los primeros d\u00edas de enero se encuentran trabajando con ni\u00f1os de las comunas de Copiap\u00f3 y Tierra Amarilla, cuyas familias voluntariamente aceptaron que sus hijos participaran de sesiones educativas online dirigidas por tutores de las 3 fundaciones.<\/p>\n\n\n\n<p>En el caso de Araucan\u00edAprende, se sumaron a este proyecto de emergencia profesionales y rescatistas del Programa Rescate Lector, quienes sin mediar retribuci\u00f3n econ\u00f3mica de por medio, tomaron la decisi\u00f3n de contribuir, \u201csoy tutora de ni\u00f1os de la regi\u00f3n de Atacama porque habiendo ejercido muchos a\u00f1os la docencia, me motiva ayudarlos a mejorar sus niveles de lectura y comprensi\u00f3n para su desarrollo personal en el futuro. Me siento enormemente satisfecha y feliz de este trabajo, por la posibilidad que me ha dado la Fundaci\u00f3n de continuar entregando mis conocimientos a los ni\u00f1os que m\u00e1s lo necesitan\u201d, coment\u00f3 Gabriela Montoya, Rescatista y tutora del plan Atacama.<\/p>\n\n\n\n<p>Debido al car\u00e1cter voluntario de la acci\u00f3n, tutores y familias asumieron la responsabilidad de reunirse virtualmente y trabajar durante todo el mes de enero. El objetivo es que cada una de las 42 familias que aceptaron la intervenci\u00f3n participen como m\u00ednimo de 8 sesiones, por medio de las cuales se busca que los ni\u00f1os atendidos adquieran: una actitud favorable hacia lectura y el aprendizaje; conocimientos elementales que le faciliten el aprendizaje de la lectura y, que las familias sepan c\u00f3mo estimular el aprendizaje de la lectura en el hogar. Para ello, los tutores utilizar\u00e1n el manual de apoyo lector en el hogar de Araucan\u00edAprende, con el que se gu\u00eda el plan del trabajo del Rescate Lector.<\/p>\n\n\n\n<p>En palabras de Carlos Dreves, Director Ejecutivo de Fundaci\u00f3n Araucan\u00edAprende, apoyar en este momento a familias de la regi\u00f3n de Atacama a trav\u00e9s de un esquema de colaboraci\u00f3n es crucial, porque marca un precedente del trabajo que se podr\u00eda concretar y ampliar en el futuro con mayores recursos. Lo que implica un desaf\u00edo y a la vez, un gran prop\u00f3sito para 3 Fundaciones-que como integrantes de la Red Por un Chile que Lee-desde distintas regiones se unieron para que ni\u00f1os y ni\u00f1as puedan continuar aprendiendo sin limitaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_47508\" class=\"pvc_stats total_only  \" data-element-id=\"47508\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Porque no importa en qu\u00e9 regi\u00f3n vivan los ni\u00f1os que requieren aprender en igualdad de condiciones, Araucan\u00edAprende junto a 2<\/p>\n","protected":false},"author":1,"featured_media":47507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[101],"tags":[],"class_list":["post-47508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"a3_pvc":{"activated":true,"total_views":61,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/47508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=47508"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/47508\/revisions"}],"predecessor-version":[{"id":47509,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/47508\/revisions\/47509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/47507"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=47508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=47508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=47508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}