{"id":47010,"date":"2023-12-21T15:18:29","date_gmt":"2023-12-21T18:18:29","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=47010"},"modified":"2023-12-21T15:18:30","modified_gmt":"2023-12-21T18:18:30","slug":"megafraude-tributario-diputada-karen-medina-pdg-emplaza-al-sii-por-transparencia-y-rendicion-de-cuentas","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2023\/12\/21\/megafraude-tributario-diputada-karen-medina-pdg-emplaza-al-sii-por-transparencia-y-rendicion-de-cuentas\/","title":{"rendered":"Megafraude tributario: Diputada Karen Medina (PDG)\u00a0 emplaza al SII por transparencia y rendici\u00f3n de cuentas"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_47010\" class=\"pvc_stats total_only  \" data-element-id=\"47010\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<ul class=\"wp-block-list\">\n<li><strong>\u201cEs fundamental conocer todos los movimientos que se realizaron en este proceso para identificar las fallas en el sistema y fortalecer los mecanismos de control\u201d, afirm\u00f3 la parlamentaria.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>A ra\u00edz de la investigaci\u00f3n por delitos tributarios en los que incurrieron m\u00e1s de 60 empresarios, defraudando al Fisco en hasta $240 mil millones, la diputada del PDG, Karen Medina, envi\u00f3 un oficio al Servicio de Impuestos Internos (SII) para conocer todas las autorizaciones, pr\u00f3rrogas, negociaciones, exenciones, repactaciones, gestiones y funcionarios involucrados durante los \u00faltimos 18 meses.<\/p>\n\n\n\n<p>Esto, debido a que el mayor fraude tributario de la historia, se concret\u00f3 a trav\u00e9s de la operaci\u00f3n de 340 contribuyentes que emitieron m\u00e1s de 100 mil facturas falsas, las cuales les permit\u00edan evadir o tener una devoluci\u00f3n de impuestos como el IVA o aduaneros. Documentos fraudulentos que se consiguieron por la compleja elaboraci\u00f3n de sociedades ficticias y con &#8220;proveedores&#8221; de estas a partir de empresas establecidas.<\/p>\n\n\n\n<p>&nbsp;\u201cEs fundamental conocer todos los movimientos que se realizaron en este proceso para identificar las fallas en el sistema y fortalecer los mecanismos de control. La transparencia y la rendici\u00f3n de cuentas son fundamentales en la construcci\u00f3n de una sociedad justa y equitativa\u201d, sostuvo la parlamentaria al ser consultada por esta iniciativa.<\/p>\n\n\n\n<p>Adem\u00e1s, Medina hizo un llamado a la entidad tributaria a \u201ccolaborar plenamente con la investigaci\u00f3n y a tomar medidas concretas para prevenir que situaciones como estas se repitan en el futuro\u201d, tras esto&nbsp; agreg\u00f3 que \u201cla confianza de los ciudadanos en nuestras instituciones es crucial, y debemos trabajar juntos para restaurarla y garantizar que el sistema tributario funcione de manera justa y eficiente para todos\u201d.<\/p>\n\n\n\n<p>\u201cLos delitos econ\u00f3micos, de cuello y corbata, son parte del crimen organizado que hace un tiempo se viene gestando en nuestro pa\u00eds y este fraude, no puede quedar impune por todo el perjuicio que significa a las arcas fiscales de Chile\u201d, critic\u00f3 la legisladora.<\/p>\n\n\n\n<p>Finalmente, asegur\u00f3 que utilizar\u00e1 todas las instancias que le permitan \u201cmejorar a\u00fan m\u00e1s el sistema. El trabajo que hizo el SII en este caso fue muy bueno y tenemos que sacar todo el aprendizaje posible para hacer los procesos de investigaci\u00f3n y de acci\u00f3n penal m\u00e1s eficientes\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_47010\" class=\"pvc_stats total_only  \" data-element-id=\"47010\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>A ra\u00edz de la investigaci\u00f3n por delitos tributarios en los que incurrieron m\u00e1s de 60 empresarios, defraudando al Fisco en<\/p>\n","protected":false},"author":1,"featured_media":47011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[2340,788,1101],"class_list":["post-47010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cuentas","tag-diputada","tag-sii"],"a3_pvc":{"activated":true,"total_views":1062,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/47010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=47010"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/47010\/revisions"}],"predecessor-version":[{"id":47012,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/47010\/revisions\/47012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/47011"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=47010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=47010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=47010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}