{"id":46838,"date":"2023-12-14T11:34:23","date_gmt":"2023-12-14T14:34:23","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=46838"},"modified":"2023-12-14T11:34:24","modified_gmt":"2023-12-14T14:34:24","slug":"asociacion-de-industrias-del-reciclaje-confirma-apoyo-a-proyecto-wte-araucania-valiosa-herramienta-para-valorizar-energeticamente-los-residuos","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2023\/12\/14\/asociacion-de-industrias-del-reciclaje-confirma-apoyo-a-proyecto-wte-araucania-valiosa-herramienta-para-valorizar-energeticamente-los-residuos\/","title":{"rendered":"Asociaci\u00f3n de Industrias del Reciclaje confirma apoyo a proyecto WTE Araucan\u00eda: \u201cvaliosa herramienta para valorizar energ\u00e9ticamente los residuos\u201d"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_46838\" class=\"pvc_stats total_only  \" data-element-id=\"46838\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>A d\u00edas de la crucial votaci\u00f3n que definir\u00e1 el futuro de la planta WTE Araucan\u00eda contin\u00faan las manifestaciones de apoyo a la iniciativa a trav\u00e9s de declaraciones. Es el caso de la Asociaci\u00f3n Nacional de Industrias del Reciclaje, quienes comunicaron que el proyecto WTE es coincidente y complementario con la labor que ellos realizan.<\/p>\n\n\n\n<p>Una manifestaci\u00f3n que despeja una de las principales pol\u00e9micas que levantaron quienes se opon\u00edan a WTE y que ten\u00eda relaci\u00f3n con un supuesto choque de roles entre el manejo de la basura a trav\u00e9s del m\u00e9todo de valorizaci\u00f3n energ\u00e9tica, con el del reciclaje de desechos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>ANIR reconoci\u00f3, en primer lugar, que WTE Araucan\u00eda \u201ccuenta con un Informe Consolidado de Evaluaci\u00f3n favorable que recomienda la \u00edntegra aprobaci\u00f3n de su Estudio de Impacto Ambiental\u201d, por lo que desde ese punto de partida, se refieren a las consecuencias que tendr\u00eda para la implementaci\u00f3n de la nueva Ley Rep, que obliga a las grandes empresas a reciclar sus desechos.<\/p>\n\n\n\n<p>\u201cComo ANIR, estamos comprometidos con la \u201cjerarqu\u00eda en el manejo de residuos\u201d, al igual que con las dem\u00e1s disposiciones que define la Ley REP, y apoyamos las acciones e iniciativas que eleven el manejo de residuos a las etapas superiores de esta jerarqu\u00eda. No obstante, existen y seguir\u00e1n existiendo ciertos tipos de materiales y residuos que por razones diversas no pueden ser prevenidos, reutilizados o reciclados. Para estos residuos, en la mayor\u00eda de los casos y, tanto desde el punto de vista medioambiental, como econ\u00f3mico, es preferible recuperar su contenido energ\u00e9tico en vez de llevarlos a eliminaci\u00f3n, tal como lo se\u00f1ala tambi\u00e9n la Comisi\u00f3n Europea en el marco de su Plan de Acci\u00f3n para la Econom\u00eda Circular\u201d, dice el documento.<\/p>\n\n\n\n<p>ANIR afirma que la evidencia cient\u00edfica que viene desde pa\u00edses como Alemania, Suecia&nbsp; o Dinamarca, donde estos procesos llevan a\u00f1os conviviendo, \u201cdemuestra que estos pa\u00edses han logrado llegar a reciclar alrededor de un 50-60% de sus residuos s\u00f3lidos domiciliarios, luego de varias d\u00e9cadas de pol\u00edticas p\u00fablicas enfocadas en la continua elevaci\u00f3n del manejo de residuos a las etapas superiores de la jerarqu\u00eda. La fracci\u00f3n restante que no se puede reciclar, es tratada y valorizada energ\u00e9ticamente en plantas Waste-to-Energy (WTE), reduciendo pr\u00e1cticamente a cero la eliminaci\u00f3n de residuos s\u00f3lidos domiciliarios en rellenos sanitarios, habiendo sido esta, adem\u00e1s, prohibida en los pa\u00edses mencionados anteriormente hace m\u00e1s de 15 a\u00f1os\u201d.<\/p>\n\n\n\n<p>\u201cParticularmente, en el caso de la Regi\u00f3n de La Araucan\u00eda, se ha ido generando una situaci\u00f3n cada vez m\u00e1s cr\u00edtica en relaci\u00f3n a la falta de adecuados sitios de disposici\u00f3n final, lo cual ha llevado a que m\u00e1s del 50% de los residuos s\u00f3lidos domiciliarios de la regi\u00f3n se trasladen a varios cientos de kil\u00f3metros de distancia a un relleno sanitario y un vertedero de la Regi\u00f3n del Biob\u00edo. Ante ese escenario, y de planificarse apropiadamente la gesti\u00f3n integral de residuos a largo plazo, la valorizaci\u00f3n energ\u00e9tica puede ser una valiosa herramienta para lograr en la Regi\u00f3n de La Araucan\u00eda un manejo sustentable de los residuos no reciclados y complementar las pol\u00edticas p\u00fablicas enfocadas en el reciclaje\u201d, finaliza la declaraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_46838\" class=\"pvc_stats total_only  \" data-element-id=\"46838\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>A d\u00edas de la crucial votaci\u00f3n que definir\u00e1 el futuro de la planta WTE Araucan\u00eda contin\u00faan las manifestaciones de apoyo<\/p>\n","protected":false},"author":1,"featured_media":46839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[155,2200],"class_list":["post-46838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temuco","tag-proyecto","tag-wte"],"a3_pvc":{"activated":true,"total_views":2106,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/46838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=46838"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/46838\/revisions"}],"predecessor-version":[{"id":46840,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/46838\/revisions\/46840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/46839"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=46838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=46838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=46838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}