{"id":44078,"date":"2023-08-21T09:35:35","date_gmt":"2023-08-21T12:35:35","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=44078"},"modified":"2023-08-21T09:35:35","modified_gmt":"2023-08-21T12:35:35","slug":"zalo-reyes-estrenan-single-y-video-postumo-a-un-ano-de-su-muerte","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2023\/08\/21\/zalo-reyes-estrenan-single-y-video-postumo-a-un-ano-de-su-muerte\/","title":{"rendered":"Zalo Reyes: Estrenan single y video p\u00f3stumo a un a\u00f1o de su muerte"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_44078\" class=\"pvc_stats total_only  \" data-element-id=\"44078\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><strong>Justo al cumplirse un a\u00f1o de su partida, llega una especial versi\u00f3n de \u201cMi caminar\u201d, canci\u00f3n cl\u00e1sica del artista que fue regrabada antes de fallecer y que hoy revive como un significativo homenaje.<\/strong><\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/DOxdP4dINBc\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<p>Este 21 de agosto se estren\u00f3 en plataformas digitales\u00a0<strong>\u201cMi caminar\u201d<\/strong>, la reversi\u00f3n registrada por Zalo Reyes junto a su nieto -y productor musical del single-, Boris Gonz\u00e1lez, quien tambi\u00e9n toc\u00f3 el piano para la ocasi\u00f3n junto a la colaboraci\u00f3n en voz de Gael y \u00c1ngela Acu\u00f1a en Cello.<br>\u00a0<br>Esta canci\u00f3n es una grabaci\u00f3n que nace en pleno tiempo de pandemia, en el estudio de la casa de\u00a0<strong>Zalo Reyes<\/strong>, como una forma de llenar la imposibilidad de presentaciones que tuvo el artista y su equipo producto del tiempo de estancamiento que gener\u00f3 el virus.\u00a0<br>\u00a0<br>De esta forma, junto a su nieto Boris, quien nace viviendo en su casa y lo acompa\u00f1a hasta el \u00faltimo d\u00eda simb\u00f3licamente desde el piano, deciden darle un espacio importante a estas grabaciones, pues desde hace muchos a\u00f1os que Zalo Reyes no alcanzaba suficiente motivaci\u00f3n y tiempo para avanzar con el proyecto debido tambi\u00e9n a las largas giras que juntos recorrieron los \u00faltimos doce\u00a0a\u00f1os de su carrera musical.<br>\u00a0<br><strong><em>\u201cSe decidi\u00f3 por este primer sencillo porque relata y retrata algo dif\u00edcil de explicar, sobre todo para quienes no conocen el primer video de la primera versi\u00f3n de &#8216;Mi caminar&#8217;, mi tata ten\u00eda un tema con su muerte, le importaba mucho el creer c\u00f3mo ser\u00eda, por esto en la primera edici\u00f3n de &#8216;Mi caminar&#8217; se muestra eso y para esta \u00faltima versi\u00f3n quise traspasar esta inquietud de \u00e9l en la realidad que termin\u00f3 siendo;\u00a0un hermoso y masivo adi\u00f3s<\/em>\u201d<\/strong>, cuenta Boris Gonz\u00e1lez, nieto de Zalo.<br>\u00a0\u00a0<br>Es as\u00ed como el sencillo\u00a0<strong>\u201cMi caminar\u201d,\u00a0<\/strong>toma un puesto importante en las composiciones que se le hicieron al artista, porque para &#8220;El gorri\u00f3n de Conchal\u00ed&#8221;, esta canci\u00f3n en particular retrata y relata a la perfecci\u00f3n la realidad que lo acompa\u00f1\u00f3 los \u00faltimos a\u00f1os de su vida:\u00a0<strong><em>\u201cMis noches, son mas noches que ma\u00f1anas\u201d\u00a0<\/em><\/strong>o frases como\u00a0<strong><em>\u201cPor m\u00e1s que toque fondo, y mi voz enmudeciera mi vida\u201d<\/em><\/strong><em>,<\/em>\u00a0pasar\u00edan a ser una suerte de poes\u00eda que hace sentido al pasar de muchos y por sobre todo al artista.<br>\u00a0<br>Est\u00e1 nueva versi\u00f3n de\u00a0<strong>\u201cMi caminar\u201d,<\/strong>\u00a0nace y se lanza por primera vez en 2008, plasmando en aquel video original lo que Zalo Reyes cre\u00eda ser\u00eda en realidad su velorio, incluyendo a quienes decidi\u00f3 invitar para esa aparici\u00f3n entre otros detalles preparados por \u00e9l mismo en esa instancia, sin dimensionar lo hoy en d\u00eda termin\u00f3 de convertirse en una nueva versi\u00f3n en audio y video que da cuenta que en realidad su velorio result\u00f3 algo mucho m\u00e1s potente de lo que imagin\u00f3, llegando a estar acompa\u00f1ado por cerca de 30 mil personas en el Gimnasio Municipal de Conchal\u00ed, donde llegaron personas de todo Chile -e incluso del extranjero- con el \u00fanico objetivo de despedirle del popular artista chileno.<br>\u00a0<br>As\u00ed fue que a pocos meses de su fallecimiento, su nieto\u00a0<strong>Boris Gonz\u00e1lez<\/strong>\u00a0tom\u00f3 la decisi\u00f3n de convertir esta \u00faltima versi\u00f3n en una canci\u00f3n y video que hace justicia y fusiona lo que Zalo Reyes imaginaba de su partida, juntando las\u00a0im\u00e1genes reales de lo que termin\u00f3 siendo una de las despedidas o velatorios m\u00e1s grandes y masivos de la historia de nuestro pa\u00eds.<br>\u00a0<br><strong><em>\u201cMis sensaciones son de un compromiso, un bello compromiso es el que me qued\u00f3 en este mundo por todo lo que mi tata me entreg\u00f3, como abuelo, como profesor, y aqu\u00ed vamos a cumplir este desaf\u00edo, con cari\u00f1o para sus fans y amigos\u201d<\/em><\/strong>, comenta Boris.<br>\u00a0<br>Sin adelantar mucho, es destacable que con este lanzamiento de\u00a0<strong>\u201cMi Caminar\u201d<\/strong>\u00a0en audio y video, comenzaremos a vivir un proceso del que pocos artistas tienen, ya que depende de su legado musical, tal como existen etapas como la\u00a0\u201crevelaci\u00f3n inicial\u201d, la \u201cIdolatr\u00eda\u201d\u00a0y la \u201ccontinuidad\u201d, para algunos transformarse en \u201cleyenda\u201d\u00a0 o \u201cpatrimonio\u201d, algunos artistas gracias al trabajo de quienes admiran y legan pueden hacer posible misiones que dejan en este planeta, tales como lanzar canciones que fueron escritas e interpretadas para ser publicadas despu\u00e9s de su partida.<br>\u00a0<br>En lo estrictamente musical, el sencillo \u201cMi caminar\u201d cuenta con un trabajo que se hizo contemplando solo una base de piano, ejecutada por su nieto y la voz inconfundible de Zalo Reyes, con una sentida y muy madura interpretaci\u00f3n y color de voz que deja traslucir una sensaci\u00f3n de \u201cdespedida\u201d o \u201c\u00faltimas interpretaciones\u201d, torn\u00e1ndose en un hermoso \u00faltimo momento del artista frente al micr\u00f3fono.<br>\u00a0<br>El single en su versi\u00f3n 2023, ser\u00e1 presentado este\u00a0<strong>lunes 21 de agosto\u00a0<\/strong>en un evento abierto gratuito (con cupos limitados) que se realizar\u00e1\u00a0<strong>desde las 16:00 horas en el sal\u00f3n de eventos Espacio Legan\u00e9s 3331, Metro Conchal\u00ed: Ceremonia del Primer A\u00f1o sin Zalo Reyes + lanzamiento sentido del videoclip<\/strong>. Tambi\u00e9n habr\u00e1 m\u00fasica en vivo, historias y proyecciones del recuerdo del artista.<br>\u00a0<br>Participan en este single, la voz de Zalo Reyes, el piano de su nieto Boris Gonz\u00e1lez, la colaboraci\u00f3n en voz de Gael, quien es fundamental en esta obra pues \u201cMi Caminar\u201d es una composici\u00f3n de Gael, la que m\u00e1s de diez\u00a0a\u00f1os antes grabar\u00edan por primera vez, sum\u00e1ndose al final de esta producci\u00f3n el hermoso Cello de \u00c1ngela Acu\u00f1a<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_44078\" class=\"pvc_stats total_only  \" data-element-id=\"44078\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Justo al cumplirse un a\u00f1o de su partida, llega una especial versi\u00f3n de \u201cMi caminar\u201d, canci\u00f3n cl\u00e1sica del artista que<\/p>\n","protected":false},"author":1,"featured_media":44079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[369],"tags":[609,372,445,6666],"class_list":["post-44078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-estreno","tag-single","tag-video","tag-zalo-reyes"],"a3_pvc":{"activated":true,"total_views":1741,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/44078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=44078"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/44078\/revisions"}],"predecessor-version":[{"id":44080,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/44078\/revisions\/44080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/44079"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=44078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=44078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=44078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}