{"id":4211,"date":"2019-06-06T16:53:18","date_gmt":"2019-06-06T19:53:18","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=4211"},"modified":"2019-06-06T16:53:18","modified_gmt":"2019-06-06T19:53:18","slug":"carabineros-y-municipalidad-de-temuco-llaman-a-no-recibir-prestamos-ilegales-y-evitar-robos-a-vehiculos-en-temuco","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2019\/06\/06\/carabineros-y-municipalidad-de-temuco-llaman-a-no-recibir-prestamos-ilegales-y-evitar-robos-a-vehiculos-en-temuco\/","title":{"rendered":"Carabineros y Municipalidad de Temuco llaman a no recibir pr\u00e9stamos ilegales y evitar robos a veh\u00edculos en Temuco"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_4211\" class=\"pvc_stats total_only  \" data-element-id=\"4211\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p style=\"text-align: justify;\">Carabineros de la 2da. Comisar\u00eda en conjunto con la Municipalidad, llegaron hasta el sector Feria Pinto y la Plaza de Armas de Temuco para hacer un llamado a la comunidad a no recibir pr\u00e9stamos ilegales conocidos popularmente como los \u201cgota a gota\u201d y prevenir el robo de veh\u00edculos o especies desde su interior.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan precis\u00f3 el jefe de operativo de la 2da. Comisar\u00eda de Temuco, Mayor Mauricio Jeldres Cid, el objetivo de la actividad fue informar a los locatarios respecto de los peligros de estos pr\u00e9stamos que se entregan con un alto inter\u00e9s, ya que existe una denuncia por amenazas de una persona que acept\u00f3 este pr\u00e9stamo y no pudo pagar las cuotas, caso que est\u00e1 investigando el OS-9 de Carabineros.<\/p>\n<p style=\"text-align: justify;\">\u201cLa idea es que los comerciantes no soliciten estos cr\u00e9ditos de manera informal, el que es conocido vulgarmente como el gota a gota. Estos grupos clandestinos juegan con la necesidad de las personas, este pr\u00e9stamo tiene un inter\u00e9s de un 20% m\u00e1s alto que cualquier otro pr\u00e9stamo normal y si no se realizan los pagos, puede terminar en agresi\u00f3n. Si la v\u00edctima es amenazada, extorsionada o si alguien conoce alg\u00fan caso, llame al 133 donde puede hacer la denuncia\u201d, se\u00f1al\u00f3 el Mayor Jeldres.<\/p>\n<p style=\"text-align: justify;\">Luego, carabineros y los representantes de la municipalidad, se trasladaron a la plaza de armas An\u00edbal Pinto de Temuco, para entregar consejos para evitar el robo de veh\u00edculos o especies desde su interior, adem\u00e1s de tel\u00e9fonos celulares por medio de los conocidos \u201clanzazos\u201d.<\/p>\n<p style=\"text-align: justify;\">El Mayor Mauricio Jeldres, precis\u00f3 que los veh\u00edculos son sustra\u00eddos entre los horarios que van desde las 22 horas a las 00 horas, principalmente en las cercan\u00edas del Hospital Regional. \u201cHay un alto porcentaje en que los veh\u00edculos son recuperados, pero es un delito que nos afecta\u201d, por lo cual recomendamos estacionar en lugares establecidos, en aparcaderos, adem\u00e1s de otras medidas como cortacorriente, traba volante, estacionar en lugares iluminados, etc.\u201d.<\/p>\n<p style=\"text-align: justify;\">La actividad cont\u00f3 adem\u00e1s con la presencia de carabineros de la oficina de integraci\u00f3n comunitaria, quienes reforzaron el mensaje preventivo en beneficio de todos los temuquenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_4211\" class=\"pvc_stats total_only  \" data-element-id=\"4211\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Carabineros de la 2da. Comisar\u00eda en conjunto con la Municipalidad, llegaron hasta el sector Feria Pinto y la Plaza de<\/p>\n","protected":false},"author":1,"featured_media":4212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[16],"tags":[125,1542,400],"class_list":["post-4211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-carabineros","tag-prestamos","tag-robos"],"a3_pvc":{"activated":true,"total_views":24,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/4211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=4211"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/4211\/revisions"}],"predecessor-version":[{"id":4213,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/4211\/revisions\/4213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/4212"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=4211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=4211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=4211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}