{"id":4202,"date":"2019-06-05T18:56:42","date_gmt":"2019-06-05T21:56:42","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=4202"},"modified":"2019-06-05T18:56:42","modified_gmt":"2019-06-05T21:56:42","slug":"diputados-inician-tramitacion-de-proyecto-de-reforma-constitucional-en-beneficio-de-adultos-mayores","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2019\/06\/05\/diputados-inician-tramitacion-de-proyecto-de-reforma-constitucional-en-beneficio-de-adultos-mayores\/","title":{"rendered":"Diputados inician tramitaci\u00f3n de proyecto de reforma constitucional en beneficio de adultos mayores"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_4202\" class=\"pvc_stats total_only  \" data-element-id=\"4202\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p style=\"text-align: justify;\">La Comisi\u00f3n de Familia y Adulto Mayor de la C\u00e1mara de Diputados resolvi\u00f3 esta semana iniciar la tramitaci\u00f3n de un proyecto de reforma constitucional que establece un Sistema Integral de Garant\u00edas y derechos de los Adultos Mayores en Chile.<\/p>\n<p style=\"text-align: justify;\">Esta iniciativa es del diputado independiente Ren\u00e9 Saffirio, que pretende ir saldando la profunda deuda de abandono y postergaciones que el Estado y la sociedad mantienen con la poblaci\u00f3n de la tercera edad de nuestro pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">\u201cLos Adultos Mayores no pueden seguir esperando, por lo que ya es hora de impulsar soluciones de fondo, para abordar las condiciones en que encuentran muchas personas de la tercera edad en Chile, como son: la pobreza, el abandono, los maltratos y las paup\u00e9rrimas pensiones que reciben la gran mayor\u00eda, s\u00f3lo por mencionar algunas de las problem\u00e1ticas que los afligen\u201d, dijo el legislador de La Araucan\u00eda.<\/p>\n<p style=\"text-align: justify;\">Este proyecto incorpora un nuevo art\u00edculo a la Constituci\u00f3n, que recalca el goce pleno de los derechos de los adultos mayores, particularmente los reconocidos por los tratados internacionales sobre derechos humanos ratificados por Chile y que se encuentran vigentes.<\/p>\n<p style=\"text-align: justify;\">\u201cEs deber del Estado garantizar a los Adultos Mayores, derechos tales como: el derecho al buen trato y a una vejez digna; el derecho a prestaciones integrales e interdisciplinarias en el cuidado de la salud; el derecho a prestaciones universales de seguridad social y a servicios sociales b\u00e1sicos; el derecho a la independencia y autonom\u00eda en la definici\u00f3n de sus planes de vida; el derecho a la participaci\u00f3n, integraci\u00f3n e inclusi\u00f3n plena y efectiva en la sociedad; y el derecho a una vida libre de violencia, prohibi\u00e9ndose toda forma de abuso o discriminaci\u00f3n arbitraria\u201d, indica el texto.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, expresa que \u201cLos \u00f3rganos del Estado deber\u00e1n dise\u00f1ar y ejecutar pol\u00edticas p\u00fablicas, con un enfoque diferencial para el goce pleno y efectivo de los derechos de los Adultos Mayores\u201d.<\/p>\n<p style=\"text-align: justify;\">Agrega que \u201cLa ley establecer\u00e1 un sistema integral de garant\u00edas y derechos de los Adultos Mayores\u201d.<\/p>\n<p style=\"text-align: justify;\">Finalmente, menciona que habr\u00e1 una Defensor\u00eda del Adulto Mayor, aut\u00f3noma de derecho p\u00fablico, con personalidad jur\u00eddica y patrimonio propio, encargada de velar por la difusi\u00f3n, promoci\u00f3n y protecci\u00f3n de los derechos de los Adultos Mayores y que una ley de qu\u00f3rum calificado determinar\u00e1 sus funciones y dem\u00e1s atribuciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_4202\" class=\"pvc_stats total_only  \" data-element-id=\"4202\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La Comisi\u00f3n de Familia y Adulto Mayor de la C\u00e1mara de Diputados resolvi\u00f3 esta semana iniciar la tramitaci\u00f3n de un<\/p>\n","protected":false},"author":1,"featured_media":4203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[249,1540,171],"class_list":["post-4202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-adultos-mayores","tag-beneficio","tag-diputados"],"a3_pvc":{"activated":true,"total_views":20,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/4202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=4202"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/4202\/revisions"}],"predecessor-version":[{"id":4204,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/4202\/revisions\/4204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/4203"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=4202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=4202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=4202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}