{"id":32740,"date":"2022-06-17T01:41:28","date_gmt":"2022-06-17T04:41:28","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=32740"},"modified":"2022-06-17T01:41:29","modified_gmt":"2022-06-17T04:41:29","slug":"multigremial-de-la-araucania-se-pronuncia-por-atentado-que-afecto-a-familia-del-convencional-constituyente-fuad-chahin","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2022\/06\/17\/multigremial-de-la-araucania-se-pronuncia-por-atentado-que-afecto-a-familia-del-convencional-constituyente-fuad-chahin\/","title":{"rendered":"Multigremial de La Araucan\u00eda se pronuncia por atentado que afect\u00f3 a familia del convencional constituyente Fuad Chahin"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_32740\" class=\"pvc_stats total_only  \" data-element-id=\"32740\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><strong>Declaraci\u00f3n P\u00fablica<\/strong><\/p>\n\n\n\n<p>Los gremios que representamos a las empresas y familias que pertenecen a los sectores productivos de La Araucan\u00eda declaramos nuestra condena al ataque terrorista perpetrado este jueves contra una hoster\u00eda de la familia del ex diputado y convencional constituyente Fuad Chahin en la comuna de Curacaut\u00edn.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Solidarizamos con esta antigua, querida y prestigiosa familia de profundo arraigo con la regi\u00f3n de La Araucan\u00eda y empatizamos con la frustraci\u00f3n de sentirse vulnerados y amedrentados por redes de terroristas y crimen organizado que solo buscan despoblar territorios, da\u00f1ar a chilenas y chilenos, mapuches y no mapuches y frenar el desarrollo y bienestar social de nuestra regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p>El terrorismo y el crimen organizado se deben enfrentar con decisi\u00f3n: reiteramos al gobierno nuestro llamado para que decrete un Estado de Emergencia m\u00e1s amplio que responda a un plan para desarticular a estas redes delictuales en todas sus acciones, como el robo de madera, el narcotr\u00e1fico, atentados contra personas, usurpaciones de predios, entre muchas otras acciones al margen de la ley.&nbsp;<\/p>\n\n\n\n<p>Estamos lejos a\u00fan de superar esta grave crisis de seguridad provocada por grupos que buscan ejercer control territorial y desestabilizar as\u00ed nuestra democracia.&nbsp;<\/p>\n\n\n\n<p><strong>MULTIGREMIAL DE LA ARAUCAN\u00cdA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_32740\" class=\"pvc_stats total_only  \" data-element-id=\"32740\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Declaraci\u00f3n P\u00fablica Los gremios que representamos a las empresas y familias que pertenecen a los sectores productivos de La Araucan\u00eda<\/p>\n","protected":false},"author":1,"featured_media":32741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[231,419,5399,5400],"class_list":["post-32740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temuco","tag-atentado","tag-familia","tag-fuad-chahin","tag-hosteria"],"a3_pvc":{"activated":true,"total_views":47,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/32740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=32740"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/32740\/revisions"}],"predecessor-version":[{"id":32742,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/32740\/revisions\/32742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/32741"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=32740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=32740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=32740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}