{"id":32737,"date":"2022-06-17T01:26:44","date_gmt":"2022-06-17T04:26:44","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=32737"},"modified":"2022-06-17T01:26:45","modified_gmt":"2022-06-17T04:26:45","slug":"sernameg-comenzara-acciones-legales-tras-firma-de-patrocinio-para-representar-a-hermana-de-la-joven-catalina-de-gorbea","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2022\/06\/17\/sernameg-comenzara-acciones-legales-tras-firma-de-patrocinio-para-representar-a-hermana-de-la-joven-catalina-de-gorbea\/","title":{"rendered":"SernamEG comenzar\u00e1 acciones legales tras firma de patrocinio para representar a hermana de la joven Catalina de Gorbea"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_32737\" class=\"pvc_stats total_only  \" data-element-id=\"32737\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>El Servicio Nacional de la Mujer y la Equidad de G\u00e9nero (SernamEG) apoyar\u00e1n a familia de la joven Catalina Navarrete Segura, de Gorbea, quien fue &nbsp;v\u00edctima de agresi\u00f3n sexual y otros delitos que le arrebataron la vida, de acuerdo a informe entregado por el Servicio M\u00e9dico Legal en La Araucan\u00eda.<\/p>\n\n\n\n<p>La Jefa Unidad en Violencia Contra las Mujeres, Paula Cifuentes Sandoval se\u00f1al\u00f3 que \u201c(\u2026) como instituci\u00f3n tomamos conocimiento del hallazgo del cuerpo sin vida de la joven de 22 a\u00f1os, Catalina Navarrete Segura, y profesionales de SernamEG se activaron para obtener antecedentes y nos pusimos en contacto con familiares de la joven para poner a disposici\u00f3n todo el apoyo que pudieran requerir (\u2026) pudiera ser que estemos, lamentablemente, frente a un nuevo femicidio consumado\u201d.&nbsp;<\/p>\n\n\n\n<p>Es as\u00ed que ante esta lamentable p\u00e9rdida el abogado de la unidad, Sergio Pinto L\u00f3pez, se re\u00fane con Lidia Navarrete Segura, hermana de la joven, quien firm\u00f3 patrocinio y ser\u00e1 representada por SernamEG en acciones legales. Estas pretenden lograr sanciones justas y ejemplificadoras.<\/p>\n\n\n\n<p>Catalina era madre de un hijo de dos a\u00f1os, hija, hermana y amiga, que la recuerdan apegada a su familia y que hoy sufren el arrebato inesperado de esta joven mujer, dejando vac\u00edos, sue\u00f1os y expectativas.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Desde el Servicio se reitera el llamado a la comunidad a denunciar si conocen mujeres en riesgos, y a quienes son v\u00edctimas de violencias en contexto de pareja o ex pareja a recurrir a los dispositivos que dispone el SernamEG:&nbsp;fono orientaci\u00f3n 1455, habilitado todos los d\u00edas del a\u00f1o las 24 horas; el chat web 1455, el whatsapp silencioso +56997007000.Tambien est\u00e1 fono Familia de Carabineros 149 y Polic\u00eda de Investigaciones 134, denunciando al fono de Fiscal\u00eda 6003330000. Y los nueve Centros de la Mujer distribuidos en la regi\u00f3n.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_32737\" class=\"pvc_stats total_only  \" data-element-id=\"32737\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El Servicio Nacional de la Mujer y la Equidad de G\u00e9nero (SernamEG) apoyar\u00e1n a familia de la joven Catalina Navarrete<\/p>\n","protected":false},"author":1,"featured_media":32738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[5398,453,419,382,134,191,2592],"class_list":["post-32737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-araucania","tag-catalina","tag-cuerpo","tag-familia","tag-gorbea","tag-hallazgo","tag-joven","tag-sernameg"],"a3_pvc":{"activated":true,"total_views":133,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/32737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=32737"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/32737\/revisions"}],"predecessor-version":[{"id":32739,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/32737\/revisions\/32739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/32738"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=32737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=32737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=32737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}