{"id":31354,"date":"2022-04-23T11:05:09","date_gmt":"2022-04-23T14:05:09","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=31354"},"modified":"2022-04-23T11:05:10","modified_gmt":"2022-04-23T14:05:10","slug":"bibliotecas-a-puertas-abiertas-teleton-celebrara-el-dia-del-libro-con-actividades-en-sus-14-institutos-del-pais","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2022\/04\/23\/bibliotecas-a-puertas-abiertas-teleton-celebrara-el-dia-del-libro-con-actividades-en-sus-14-institutos-del-pais\/","title":{"rendered":"Bibliotecas a puertas abiertas: Telet\u00f3n celebrar\u00e1 el D\u00eda del Libro con actividades en sus 14 institutos del pa\u00eds"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_31354\" class=\"pvc_stats total_only  \" data-element-id=\"31354\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<ul class=\"wp-block-list\"><li>Pacientes, usuarios y familias que se atienden en la instituci\u00f3n podr\u00e1n disfrutar de actividades de lectura y entretenci\u00f3n este lunes 25 de abril. La instituci\u00f3n ha habilitado desde 2018 bibliotecas con amplias colecciones de libros con apoyo del Ministerio de las Culturas, las Artes y el Patrimonio.<\/li><\/ul>\n\n\n\n<p>Aperturas tem\u00e1ticas, disfraces, cuenta cuentos, din\u00e1micas, regalos y donaciones, son algunas de las actividades que se llevar\u00e1n a cabo este lunes 25 de abril en todos los institutos Telet\u00f3n con motivo de la celebraci\u00f3n del&nbsp;<strong>D\u00eda Internacional del Libro.<\/strong><\/p>\n\n\n\n<p>La iniciativa tiene por nombre&nbsp;<strong>\u201cBibliotecas a puertas abiertas\u201d<\/strong>&nbsp;y permitir\u00e1 la&nbsp;<strong>apertura de las bibliotecas de los institutos Telet\u00f3n de Iquique, Antofagasta, Calama, Copiap\u00f3, Coquimbo, Santiago, Concepci\u00f3n, Temuco, Valdivia y Puerto Montt.<\/strong>&nbsp;En aquellos centros en que las bibliotecas se encuentran en trabajos o proyectos de obra (Arica, Valpara\u00edso, Talca y Coyhaique), se habilitar\u00e1n espacios especiales para realizar estas actividades de celebraci\u00f3n.<\/p>\n\n\n\n<p><strong>\u00bfQui\u00e9nes pueden participar?<\/strong>&nbsp;Todas las familias de pacientes o usuarios que se atienden en alguno de los centros Telet\u00f3n de Arica a Coyhaique, y que ese d\u00eda tengan atenciones presenciales.<\/p>\n\n\n\n<p><strong>\u201cLa posibilidad de tener acceso a la cultura y la lectura en cada una de las salas de espera de los institutos Telet\u00f3n, es otra manera de brindar un servicio de calidad a nuestros usuarios y sus familias.<\/strong>&nbsp;Las diez bibliotecas que tenemos habilitadas nos permite acercar este maravilloso mundo de los libros a miles de personas que, muchas veces, no tienen el tiempo para ir a pedir un libro en pr\u00e9stamo, y ac\u00e1 est\u00e1n a muy f\u00e1cil acceso para llevarlos a sus casas o leer mientras realizan la espera de sus terapias\u201d, explica&nbsp;<strong>Aldo Orrigoni,&nbsp;<\/strong>director de Gesti\u00f3n Social y Voluntariado de Telet\u00f3n.<\/p>\n\n\n\n<p><strong>El proyecto de bibliotecas de Telet\u00f3n naci\u00f3 en 2018 con una postulaci\u00f3n a fondos del Ministerio de las Culturas, las Artes y el Patrimonio para habilitar la primera biblioteca Telet\u00f3n en el instituto de Santiago, as\u00ed como la compra de una colecci\u00f3n bibliogr\u00e1fica.&nbsp;<\/strong>&nbsp;Despu\u00e9s de entregado este primer proyecto, se firm\u00f3 un convenio de cooperaci\u00f3n de trabajo directo con el ministerio, a trav\u00e9s de su programa BiblioRedes, por el cual Telet\u00f3n se comprometi\u00f3 a aportar las obras civiles de los proyectos y el Estado a entregar equipamiento de mobiliario, computadores y colecciones bibliogr\u00e1ficas.<\/p>\n\n\n\n<p>A esto se suma que desde 2021 tambi\u00e9n se realizan capacitaciones para voluntarios en mediaci\u00f3n de lectura, software de pr\u00e9stamo de libros, clubes de lectura para pacientes, cuidadores y voluntarios y otras actividades.<\/p>\n\n\n\n<p>\u201cEstas bibliotecas son gestionadas por voluntarios y voluntarias de Telet\u00f3n, lo que tambi\u00e9n aporta a la calidez. Ellos realizan actividades de mediaci\u00f3n lectora, administran el sistema de pr\u00e9stamos de libros y consultas en sala, de igual manera, formulan diversas actividades tem\u00e1ticas durante el a\u00f1o para promover la lectura y el amor por los libros\u201d, a\u00f1ade Aldo Orrigoni.<\/p>\n\n\n\n<p><strong>A la fecha, las diez bibliotecas con que cuenta Telet\u00f3n en todo el pa\u00eds re\u00fanen m\u00e1s de 5.600 libros y textos disponibles para los pacientes, las familias, trabajadores y voluntarios de la instituci\u00f3n.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_31354\" class=\"pvc_stats total_only  \" data-element-id=\"31354\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Pacientes, usuarios y familias que se atienden en la instituci\u00f3n podr\u00e1n disfrutar de actividades de lectura y entretenci\u00f3n este lunes<\/p>\n","protected":false},"author":1,"featured_media":31355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[1462,3920,501,1273],"class_list":["post-31354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temuco","tag-actividades","tag-bibliotecas","tag-dia","tag-libro"],"a3_pvc":{"activated":true,"total_views":70,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/31354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=31354"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/31354\/revisions"}],"predecessor-version":[{"id":31356,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/31354\/revisions\/31356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/31355"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=31354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=31354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=31354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}