{"id":29824,"date":"2022-03-02T11:45:12","date_gmt":"2022-03-02T14:45:12","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=29824"},"modified":"2022-03-02T11:45:14","modified_gmt":"2022-03-02T14:45:14","slug":"diputado-rathgeb-emplaza-al-nuevo-gobierno-si-no-quieren-estado-de-emergencia-es-necesario-que-transparenten-sus-medidas-en-materia-de-seguridad","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2022\/03\/02\/diputado-rathgeb-emplaza-al-nuevo-gobierno-si-no-quieren-estado-de-emergencia-es-necesario-que-transparenten-sus-medidas-en-materia-de-seguridad\/","title":{"rendered":"Diputado Rathgeb emplaza al nuevo Gobierno: \u201cSi no quieren Estado de Emergencia, es necesario que transparenten sus medidas en materia de seguridad\u201d"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_29824\" class=\"pvc_stats total_only  \" data-element-id=\"29824\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><strong>Rathgeb indic\u00f3 que si la nueva administraci\u00f3n de entrada descart\u00f3 el despliegue de Fuerzas Armadas en las provincias de Biob\u00edo, Arauco, Malleco y Caut\u00edn, deben se\u00f1alar cuales ser\u00e1n las medidas que llevar\u00e1n a cabo en materia de seguridad.<\/strong><\/p>\n\n\n\n<p>Las nuevas autoridades del Gobierno que encabezar\u00e1 el Presidente Gabriel Boric, anunciaron que no renovar\u00e1n las extensiones del Estado de Emergencia para las provincias de Biob\u00edo, Arauco, Malleco y Caut\u00edn, una vez que asuman el cargo, ante lo cual el diputado de Renovaci\u00f3n Nacional por La Araucan\u00eda, Jorge Rathgeb Schifferli, realiz\u00f3 un emplazamiento al futuro Ejecutivo.<\/p>\n\n\n\n<p>Rathgeb indic\u00f3 que la futura administraci\u00f3n debe entregar una hoja de ruta clara en materia de seguridad para la Macrozona Sur y que si descartan la presencia de Fuerzas Armadas en terreno, se debe transparentar por el bien de la ciudadan\u00eda cuales ser\u00e1n las medidas que se adoptar\u00e1n.<\/p>\n\n\n\n<p>El parlamentario se\u00f1al\u00f3 que la actual administraci\u00f3n estuvo al \u201cdebe\u201d en este tema, pero la ciudadan\u00eda entreg\u00f3 el respaldo a la decisi\u00f3n de los \u00faltimos meses del mandato, de tener el despliegue de militares en la zona, por lo cual es inexplicable que no se siga extendiendo la medida, por parte del Gobierno que asumir\u00e1 a contar del 11 de marzo.<\/p>\n\n\n\n<p>En su condici\u00f3n de actual presidente regional de RN, Rathgeb, espera que se puedan entregar luces claras, respecto a un tema sensible y delicado, que es una de las prioridades en La Araucan\u00eda.<\/p>\n\n\n\n<p>\u201cLa futura administraci\u00f3n descart\u00f3 de plano seguir con el Estado de Emergencia, lo cual no comparto en absoluto, pero lo llamativo es que no dijeron o adelantaron nada de lo que har\u00e1n en materia de seguridad, que es un tema primordial para la Regi\u00f3n y donde el actual Gobierno estuvo en deuda. Los habitantes necesitan saber qu\u00e9 ocurrir\u00e1 o que se har\u00e1, porque si anunciaron que no continuar\u00e1n con la presencia de militares, la l\u00f3gica es que hayan dicho el c\u00f3mo resolver\u00e1n o abordar\u00e1n la situaci\u00f3n para que no ocurran hechos de car\u00e1cter violentista y terrorista, donde el actual Gobierno no pudo encontrar una soluci\u00f3n concreta. Emplazo de manera p\u00fablica a que el gabinete del pr\u00f3ximo Presidente, indique sus medidas\u201d, se\u00f1al\u00f3 Rathgeb.<\/p>\n\n\n\n<p>El diputado traiguenino espera que se escuche a la ciudadan\u00eda o se pueda aplicar una consulta, donde los resultados ser\u00e1n diametralmente opuestos a lo que piensan las autoridades entrantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_29824\" class=\"pvc_stats total_only  \" data-element-id=\"29824\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Rathgeb indic\u00f3 que si la nueva administraci\u00f3n de entrada descart\u00f3 el despliegue de Fuerzas Armadas en las provincias de Biob\u00edo,<\/p>\n","protected":false},"author":1,"featured_media":21551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[154,4410,206,399],"class_list":["post-29824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-diputado","tag-estado-de-emergencia","tag-gobierno","tag-seguridad"],"a3_pvc":{"activated":true,"total_views":39,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/29824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=29824"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/29824\/revisions"}],"predecessor-version":[{"id":29825,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/29824\/revisions\/29825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/21551"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=29824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=29824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=29824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}