{"id":29746,"date":"2022-02-28T11:44:16","date_gmt":"2022-02-28T14:44:16","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=29746"},"modified":"2022-02-28T11:44:17","modified_gmt":"2022-02-28T14:44:17","slug":"filarmonica-de-temuco-presento-concierto-online-en-el-marco-del-aniversario-141-de-temuco","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2022\/02\/28\/filarmonica-de-temuco-presento-concierto-online-en-el-marco-del-aniversario-141-de-temuco\/","title":{"rendered":"Filarm\u00f3nica de Temuco present\u00f3 concierto online en el marco del Aniversario 141 de Temuco"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_29746\" class=\"pvc_stats total_only  \" data-element-id=\"29746\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em>El concierto se encuentra disponible en el canal de youtube del Teatro Municipal de Temuco.<\/em><\/p>\n\n\n\n<p>Como ya es tradici\u00f3n, la Orquesta Filarm\u00f3nica de Temuco estuvo nuevamente presente en el marco de las actividades organizadas para conmemorar los 141 a\u00f1os de fundaci\u00f3n de la ciudad de Temuco. Sin embargo, debido a la fase en que se encuentra la comuna y que reduce la cantidad de aforo para espacios cerrados, como lo es el Teatro Municipal Camilo Salvo, el concierto fue grabado y se transmiti\u00f3 v\u00eda online a trav\u00e9s de su canal de youtube.<\/p>\n\n\n\n<p>Respecto a la tradicional presentaci\u00f3n y destacando el gran aporte cultural que entrega el Teatro Municipal a la comunidad, el alcalde de Temuco, Roberto Neira Aburto sostuvo que \u201chemos tenido un hermoso concierto de la Orquesta Filarm\u00f3nica en el contexto de la celebraci\u00f3n de nuestros 141 a\u00f1os, por ello quiero adem\u00e1s destacar a los elencos estables del teatro municipal y todo el trabajo que han realizado durante todos estos a\u00f1os e instar a la comunidad tambi\u00e9n a participar de las actividades del teatro y en este caso, seguir este concierto desde la comodidad de su hogar\u201d, indic\u00f3.<\/p>\n\n\n\n<p>Para la Orquesta Filarm\u00f3nica de Temuco estar presente en las actividades de celebraci\u00f3n es algo significativo, as\u00ed lo indic\u00f3 su director David Ayma. \u201cCreo que somos tambi\u00e9n parte de la tradici\u00f3n, y tambi\u00e9n somos parte de la comunidad. La filarm\u00f3nica de Temuco ha crecido junto con lo que ha crecido la ciudad, y para nosotros es siempre un placer poder estar en estas actividades de celebraci\u00f3n, porque sentimos que somos parte importante de lo que es la cultura de nuestra ciudad\u201d, sostuvo.<\/p>\n\n\n\n<p>El concierto online fue un extracto del concierto que en enero la Filarm\u00f3nica present\u00f3 en Las Semanas Musicales de Frutillar en su temporada 54, y que en esta oportunidad busc\u00f3 deleitar a los temuquenses con reconocidas melod\u00edas de Johann Strauss II a quien se le conoce como el rey de los vals. \u201cPara este concierto presentamos parte de ese programa, las piezas que son m\u00e1s festivas, alegres, m\u00e1s cercanas, busc\u00e1bamos eso, una serie de piezas que pudiesen sentirse parte del p\u00fablico, que fuese simplemente sentar a escuchar y disfrutar\u201d, indic\u00f3 David Ayma, director de la Orquesta Filarm\u00f3nica de Temuco.<\/p>\n\n\n\n<p>El concierto est\u00e1 disponible en el canal de youtube del Teatro Municipal de Temuco.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_29746\" class=\"pvc_stats total_only  \" data-element-id=\"29746\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El concierto se encuentra disponible en el canal de youtube del Teatro Municipal de Temuco. Como ya es tradici\u00f3n, la<\/p>\n","protected":false},"author":1,"featured_media":29747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[86],"tags":[496,1010,2555,78],"class_list":["post-29746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-panoramas","tag-aniversario","tag-concierto","tag-filarmonica","tag-temuco"],"a3_pvc":{"activated":true,"total_views":48,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/29746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=29746"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/29746\/revisions"}],"predecessor-version":[{"id":29748,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/29746\/revisions\/29748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/29747"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=29746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=29746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=29746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}