{"id":2834,"date":"2019-04-10T15:42:39","date_gmt":"2019-04-10T18:42:39","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=2834"},"modified":"2019-04-10T15:42:39","modified_gmt":"2019-04-10T18:42:39","slug":"nuevo-rodoviario-fue-inaugurado-en-la-comuna-de-lautaro","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2019\/04\/10\/nuevo-rodoviario-fue-inaugurado-en-la-comuna-de-lautaro\/","title":{"rendered":"Nuevo Rodoviario fue inaugurado en la comuna de Lautaro"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_2834\" class=\"pvc_stats total_only  \" data-element-id=\"2834\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #ff6600;\">La obra contempl\u00f3 una inversi\u00f3n superior a los 750 millones de pesos.<\/span><\/p>\n<p style=\"text-align: justify;\">Con el tradicional corte de cinta de las autoridades se dio por inaugurado el nuevo rodoviario de la comuna de Lautaro, el cual fue un proyecto anhelado por la comunidad y que viene a ordenar y modernizar el sistema de transporte p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">La ceremonia que marc\u00f3 la puesta en marcha del recinto estuvo encabezada por el alcalde Ra\u00fal Schifferli y el Seremi de Transportes, Luis Calder\u00f3n en representaci\u00f3n del Intendente de La Araucan\u00eda, adem\u00e1s de estar presentes Parlamentarios, Seremi de Gobierno, Consejeros regionales, Concejales y comunidad en general.<\/p>\n<p style=\"text-align: justify;\">Con cerca de 40 mil habitantes, Lautaro ya cuenta con un terminal de buses interprovincial que brinde las condiciones m\u00ednimas de comodidad al creciente n\u00famero de pasajeros que van hacia distintos destinos del pa\u00eds. Cabe recordar, que los buses deb\u00edan estacionar frente a sus agencias de ventas de pasajes en diferentes calles c\u00e9ntricas de la ciudad, generando inconvenientes en el tr\u00e1nsito.<\/p>\n<p style=\"text-align: justify;\">El alcalde de Lautaro Ra\u00fal Schifferli, indic\u00f3 al respecto que \u201cestamos muy contentos de poder tener el primer terminal de buses en Lautaro, lo que le va a dar dignidad a los pasajeros que viajan a sectores rurales, a Santiago y a distintas partes de la regi\u00f3n y el pa\u00eds. Este recinto funcionar\u00e1 a partir de las 6:00 de la ma\u00f1ana hasta las 00:00 hrs, ya est\u00e1 todo implementado, cuenta con seguridad, adem\u00e1s tiene una cafeter\u00eda, van a haber guardias las 24 horas, por lo que nos queda solo agradecer al Gobierno Regional\u201d, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Mientras que el Seremi de Transportes, Luis Calder\u00f3n sostuvo que \u201cse trata de una tremenda obra en cuanto a infraestructura y viene a entregar dignidad y satisfacer una necesidad de ya no un pueblo, porque Lautaro hace tiempo que ya es una ciudad. Todas esas esperas que se hac\u00edan con fr\u00edo y con lluvia ya no van a suceder m\u00e1s y eso a nosotros como Gobierno nos pone muy contentos\u201d, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">La obra contempl\u00f3 una inversi\u00f3n superior a los 750 millones de pesos, financiados a trav\u00e9s del Gobierno Regional y recursos municipales, que complementaron el presupuesto, con el fin de acelerar su funcionamiento.<\/p>\n<p style=\"text-align: justify;\">El proyecto considera 10 andenes cubiertos, sala de espera, boleter\u00edas, ba\u00f1os p\u00fablicos, cafeter\u00eda, estacionamientos particulares y para taxiscolectivos, entre otras instalaciones. A la fecha existe la confirmaci\u00f3n de siete empresas de buses que arrendaron oficinas de venta de pasajes, de las ocho disponibles en el nuevo recinto, con destinos al norte hasta Santiago-Valpara\u00edso y al sur hasta Puerto Montt.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_2834\" class=\"pvc_stats total_only  \" data-element-id=\"2834\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La obra contempl\u00f3 una inversi\u00f3n superior a los 750 millones de pesos. Con el tradicional corte de cinta de las<\/p>\n","protected":false},"author":1,"featured_media":2835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[101],"tags":[202,745,146,1121],"class_list":["post-2834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-alcalde","tag-autoridades","tag-comuna","tag-rodoviario"],"a3_pvc":{"activated":true,"total_views":125,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/2834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=2834"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/2834\/revisions"}],"predecessor-version":[{"id":2836,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/2834\/revisions\/2836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/2835"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=2834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=2834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=2834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}