{"id":25555,"date":"2021-09-28T11:34:03","date_gmt":"2021-09-28T14:34:03","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=25555"},"modified":"2021-09-28T11:34:04","modified_gmt":"2021-09-28T14:34:04","slug":"los-sauces-quiere-concretar-viejo-anhelo-de-contar-con-un-acceso-al-parque-nahuelbuta","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/09\/28\/los-sauces-quiere-concretar-viejo-anhelo-de-contar-con-un-acceso-al-parque-nahuelbuta\/","title":{"rendered":"Los Sauces quiere concretar viejo anhelo de contar con un acceso al Parque Nahuelbuta"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_25555\" class=\"pvc_stats total_only  \" data-element-id=\"25555\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em>En una reuni\u00f3n de trabajo coordinada por la senadora Carmen Gloria Aravena, Conaf se comprometi\u00f3 a revisar la factibilidad de esta iniciativa.<\/em><\/p>\n\n\n\n<p>Revisar diversas alternativas t\u00e9cnicas que permitan contar con un acceso vial al Parque Nacional Nahuelbuta desde la comuna de Los Sauces, fue el compromiso que adquiri\u00f3 el Director Ejecutivo de Conaf, Rodrigo Munita, junto al gerente de \u00c1reas Silvestres Protegidas, quienes explicaron que este Parque es una de las zonas contempladas en el Plan Impulso Araucan\u00eda, por lo que el estudio necesario para concretar este viejo anhelo comunal tendr\u00e1 un sentido de urgencia.<\/p>\n\n\n\n<p>\u201cDentro de los cuatro Parques priorizados del Plan Impulso Araucan\u00eda, Nahuelbuta es el que en \u00e9stos momentos tiene nuestra dedicaci\u00f3n. Por lo tanto, esperamos poder concretar una gran inversi\u00f3n del orden de $2.400 millones. En un informe previo del 2018, nuestro equipo relev\u00f3 un problema con una intervenci\u00f3n que habr\u00eda que hacer en unos 2 kil\u00f3metros al interior del Parque, debido a la presencia de Araucarias y otras especies protegidas, por lo cual debemos revisar otras alternativas de acceso\u201d, indic\u00f3 el gerente de \u00c1reas Silvestres Protegidas, \u00cdtalo Rossi.<\/p>\n\n\n\n<p>Por su parte, la senadora Carmen Gloria Aravena, agradeci\u00f3 la voluntad de Conaf y de todos los actores involucrados en esta iniciativa. \u201cTras esta reuni\u00f3n con Conaf, representantes del Turismo, concejales de Los Sauces y la Municipalidad, vamos a retomar un objetivo que la comunidad persigue desde hace m\u00e1s de 10 a\u00f1os. El Director de Conaf nos ha se\u00f1alado que se volver\u00e1 a revisar una carpeta t\u00e9cnica, una solicitud que hoy est\u00e1 bajo el contexto de priorizaci\u00f3n para el Parque Nahuelbuta por parte del Gobierno\u201d.<\/p>\n\n\n\n<p>Al respecto, la concejal Lucinda Henr\u00edquez, una de las propulsoras de esta iniciativa indic\u00f3: \u201cSon a\u00f1os los que hemos luchado por poder concretar este sue\u00f1o, incluso desde antes de ser concejal he trabajado en este mismo objetivo, poniendo en valor nuestros productos locales. Estoy muy contenta por el resultado de esta reuni\u00f3n, porque vemos que por primera vez est\u00e1n las voluntades de todos los actores involucrados y contamos con el apoyo de la Senadora Aravena para dar seguimiento a este proyecto\u201d.<\/p>\n\n\n\n<p>Finalmente, desde el municipio, Cristian Torres, administrador municipal de Los Sauces, explic\u00f3 que la posibilidad de contar con un acceso al Parque Nahuelbuta permitir\u00e1 un desarrollo tur\u00edstico y el rescate del patrimonio end\u00e9mico y cultural de la comuna.<\/p>\n\n\n\n<p>\u201cPara nosotros como municipalidad y para el alcalde Luis Mella, esto es un enorme desaf\u00edo, pues ya se est\u00e1 trabajando con el objetivo de reconvertir nuestra comuna. De la mano de este proyecto, la conectividad ser\u00e1 muy importante, para que los emprendedores y campesinos puedan bajar con sus productos desde la zona alta. Adem\u00e1s, se potenciar\u00e1 la hoteler\u00eda y con el esfuerzo de emprendedores podremos poner en valor nuestra gastronom\u00eda, considerando que somos la capital de la Rosa Mosqueta\u201d, se\u00f1al\u00f3 Torres.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que de acuerdo a estudios previos, la comuna de Los Sauces posee tres potenciales rutas de acceso al Parque Nacional Nahuelbuta; a trav\u00e9s de la Ruta 240, con una intervenci\u00f3n de 38 kil\u00f3metros en el l\u00edmite con Pur\u00e9n, en la misma Ruta por el sector de Los Toldos, donde se requiere una intervenci\u00f3n de 35 kil\u00f3metros que cuentan con restricci\u00f3n de acceso por parte de un privado y, finalmente, a trav\u00e9s de la Ruta 232, donde se requiere una intervenci\u00f3n de 39 kil\u00f3metros por el sector de Miraflores, donde existe una restricci\u00f3n para intervenir 2 kil\u00f3metros, dada la presencia de especies protegidas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"480\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/09\/Parque-Nahuelbuta2.jpg\" alt=\"\" class=\"wp-image-25557\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_25555\" class=\"pvc_stats total_only  \" data-element-id=\"25555\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>En una reuni\u00f3n de trabajo coordinada por la senadora Carmen Gloria Aravena, Conaf se comprometi\u00f3 a revisar la factibilidad de<\/p>\n","protected":false},"author":1,"featured_media":25556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[425,2145,279,2065],"class_list":["post-25555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-araucania","tag-conaf","tag-nahuelbuta","tag-parque","tag-senadora"],"a3_pvc":{"activated":true,"total_views":50,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/25555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=25555"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/25555\/revisions"}],"predecessor-version":[{"id":25558,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/25555\/revisions\/25558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/25556"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=25555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=25555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=25555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}