{"id":22659,"date":"2021-06-23T17:09:27","date_gmt":"2021-06-23T20:09:27","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=22659"},"modified":"2021-06-23T17:09:32","modified_gmt":"2021-06-23T20:09:32","slug":"iniciativa-bibliotecas-rurales-para-chile-entrega-libros-y-publicaciones-de-fucoa-a-lo-largo-del-pais","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/06\/23\/iniciativa-bibliotecas-rurales-para-chile-entrega-libros-y-publicaciones-de-fucoa-a-lo-largo-del-pais\/","title":{"rendered":"Iniciativa \u201cBibliotecas Rurales para Chile\u201d entrega libros y publicaciones de FUCOA a lo largo del pa\u00eds"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_22659\" class=\"pvc_stats total_only  \" data-element-id=\"22659\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><br><em>En el marco del concurso Historias de Nuestra Tierra y sus diversas iniciativas culturales y de difusi\u00f3n, la fundaci\u00f3n ligada al Ministerio de Agricultura puso a disposici\u00f3n de la comunidad educativa y el mundo rural del pa\u00eds toda su producci\u00f3n editorial, adem\u00e1s de gu\u00edas educativas para apoyar el desarrollo de las y los escolares.<\/em><\/p>\n\n\n\n<p><strong>Santiago, 15 de junio de 2021.<\/strong><em>&#8211;<\/em>&nbsp;A la par con el concurso Historias de Nuestra Tierra 2021, que rescata y difunde historias, relatos, mitos, tradiciones y sabidur\u00eda del mundo rural del pa\u00eds, este a\u00f1o la Fundaci\u00f3n de Comunicaciones, Capacitaci\u00f3n y Cultura del Agro (FUCOA) del Ministerio de Agricultura est\u00e1 impulsando su iniciativa \u201cBibliotecas Rurales para Chile\u201d, cuyo objetivo es apoyar la educaci\u00f3n y revalorizar la cultura en los territorios rurales, a trav\u00e9s de la entrega de sets de libros y publicaciones impresas de la fundaci\u00f3n a municipios, escuelas, comunidades y centros educativos y\/o culturales.<\/p>\n\n\n\n<p>Esta entrega de bibliotecas a lo largo del pa\u00eds responde al compromiso de FUCOA de difundir y revalorizar la cultura rural, algo que la instituci\u00f3n ha reforzado especialmente en el contexto de pandemia, con el fin de apoyar las actividades en las comunidades educativas y en el entorno familiar.&nbsp;<\/p>\n\n\n\n<p>La Directora Ejecutiva de FUCOA, Francisca Martin, destac\u00f3 que a lo largo de su historia, la fundaci\u00f3n ha desarrollado diversas publicaciones editoriales, entregando a la comunidad importantes fuentes de informaci\u00f3n, difusi\u00f3n y preservaci\u00f3n de la cultura rural. \u201cA trav\u00e9s de \u2018Bibliotecas Rurales para Chile\u2019, estamos entregando libros del concurso Historias de Nuestra Tierra, as\u00ed como \u2018La tonada de Margot Loyola\u2019, dedicado a la vida y obra de La Maestra; \u2018Greda Viva\u2019, sobre la tradicional alfarer\u00eda de Pomaire; y ejemplares del Diario Nuestra Tierra, entre otras publicaciones\u201d, detall\u00f3.<\/p>\n\n\n\n<p>Uno de los t\u00edtulos disponibles dentro de estas bibliotecas y que mayor inter\u00e9s ha generado entre las y los lectores es \u201cMe lo cont\u00f3 mi abuelito\u201d, que recoge los cuentos ganadores en la categor\u00eda hom\u00f3nima del concurso Historias de Nuestra Tierra, escritos por ni\u00f1os, ni\u00f1as y j\u00f3venes provenientes de diversas localidades a lo largo del pa\u00eds. Asimismo, los sets tambi\u00e9n incluyen ejemplares del libro \u201cAntolog\u00eda\u201d, que recopila los cuentos y poemas ganadores escritos por participantes de 18 a\u00f1os y m\u00e1s.<\/p>\n\n\n\n<p>A la fecha, 14 bibliotecas han sido entregas en las regiones de Los lagos, Ays\u00e9n, Los R\u00edos, Coquimbo y Antofagasta, destacando en esta \u00faltima regi\u00f3n la entrega en el poblado rural de Toconce, al transformarse en la primera biblioteca de la localidad.<\/p>\n\n\n\n<p>Junto con las entregas de ejemplares impresos a trav\u00e9s de esta iniciativa, FUCOA ha puesto a disposici\u00f3n de toda la comunidad sus libros y publicaciones en versiones digitales, para su descarga gratuita y\/o lectura online. Para acceder a ellos, basta ingresar al sitio web de la fundaci\u00f3n, men\u00fa Productos, seleccionando Publicaciones, cuyo link directo es&nbsp;<a href=\"https:\/\/www.fucoa.cl\/productos\/publicaciones\/\">https:\/\/www.fucoa.cl\/productos\/publicaciones\/<\/a><\/p>\n\n\n\n<p><strong>Convocatoria abierta<\/strong><\/p>\n\n\n\n<p>En este contexto, cabe destacar que el concurso Historias de Nuestra Tierra, que cumple 29 a\u00f1os recopilando historias, mitos, leyendas, vivencias y relatos inspirados en la realidad y caracter\u00edsticas del mundo rural y campesino del pa\u00eds, ya inici\u00f3 su convocatoria 2021 para que ni\u00f1os, ni\u00f1as, j\u00f3venes y adultos de todo el pa\u00eds puedan participar a trav\u00e9s de sus categor\u00edas de Cuento (todo p\u00fablico), Poema (todo p\u00fablico), Dibujo (estudiantes de Ense\u00f1anza B\u00e1sica y Media) y Fotograf\u00eda (mayores de 18 a\u00f1os).<\/p>\n\n\n\n<p>Las categor\u00edas de Cuento y Poema cuentan con premios nacionales y regionales, consistentes en tablets, sets de escritor e incentivos econ\u00f3micos. A nivel nacional, los ganadores se eligen entre todos los primeros lugares regionales. En tanto, los premios para las categor\u00edas de Dibujo y Fotograf\u00eda son nacionales; se eligen primer, segundo y tercer lugar, adem\u00e1s de premios especiales. Asimismo, y por segundo a\u00f1o consecutivo, tambi\u00e9n se premiar\u00e1 con computadores a tres establecimientos educacionales rurales que motiven a sus estudiantes a participar en el concurso, lo que adem\u00e1s permite apoyar la labor educativa de estas escuelas, tan necesarias y fundamentales para sus respectivas comunidades.<\/p>\n\n\n\n<p>Las obras deben ser enviadas a trav\u00e9s del renovado sitio web&nbsp;<a href=\"http:\/\/www.historiasdenuestratierra.cl\/\">www.historiasdenuestratierra.cl<\/a>, donde tambi\u00e9n est\u00e1n disponibles las bases del concurso, resultados anteriores, Galer\u00eda de Ganadores, material educativo y m\u00e1s informaci\u00f3n sobre el certamen, cuya convocatoria es hasta el 31 de agosto.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_22659\" class=\"pvc_stats total_only  \" data-element-id=\"22659\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>En el marco del concurso Historias de Nuestra Tierra y sus diversas iniciativas culturales y de difusi\u00f3n, la fundaci\u00f3n ligada<\/p>\n","protected":false},"author":1,"featured_media":22660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[101],"tags":[3920,662,3921],"class_list":["post-22659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-bibliotecas","tag-libros","tag-publicaciones"],"a3_pvc":{"activated":true,"total_views":32,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/22659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=22659"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/22659\/revisions"}],"predecessor-version":[{"id":22661,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/22659\/revisions\/22661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/22660"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=22659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=22659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=22659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}