{"id":22451,"date":"2021-06-14T18:41:28","date_gmt":"2021-06-14T21:41:28","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=22451"},"modified":"2021-06-14T18:41:30","modified_gmt":"2021-06-14T21:41:30","slug":"senadora-aravena-juntos-demostramos-que-se-puede-luciano-rivas-sera-un-gran-gobernador-en-la-araucania","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/06\/14\/senadora-aravena-juntos-demostramos-que-se-puede-luciano-rivas-sera-un-gran-gobernador-en-la-araucania\/","title":{"rendered":"Senadora Aravena: \u201cJuntos demostramos que se puede, Luciano Rivas ser\u00e1 un gran Gobernador en La Araucan\u00eda\u201d"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_22451\" class=\"pvc_stats total_only  \" data-element-id=\"22451\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><em>La parlamentaria esper\u00f3 los resultados y celebr\u00f3 el triunfo de Luciano Rivas en su comando, junto al candidato presidencial Sebasti\u00e1n Sichel.<\/em><\/p>\n\n\n\n<p>Emocionada por el gran triunfo de Luciano Rivas, quien asumir\u00e1 como primer gobernador de la regi\u00f3n de La Araucan\u00eda, la senadora Carmen Gloria Aravena manifest\u00f3 que con esta hist\u00f3rica elecci\u00f3n inicia una descentralizaci\u00f3n efectiva donde las regiones y sus gobernadores ser\u00e1n protagonistas.<\/p>\n\n\n\n<p>La parlamentaria (independiente por la bancada de RN), junto al candidato presidencial independiente, Sebasti\u00e1n Sichel, y otros parlamentarios de Chile Vamos, acompa\u00f1aron a Luciano Rivas a esperar los resultados y celebrar el triunfo de quien presidir\u00e1 el Consejo Regional (CORE) y podr\u00e1 poner urgencia y prioridad a diversos proyectos regionales.<\/p>\n\n\n\n<p>\u201cEstamos felices con el triunfo de Luciano Rivas en La Araucan\u00eda, le agradecemos por el gran trabajo realizado en las 32 comunas de nuestra regi\u00f3n. Sab\u00edamos que \u00e9l era la persona indicada para ser nuestro primer gobernador regional. Valoro enormemente la uni\u00f3n de la centro derecha y de Chile Vamos, juntos demostramos que se puede y somos capaces de lograr el triunfo. La Araucan\u00eda necesitaba de un gobernador joven y comprometido con la ciudadan\u00eda. Felicidades y el mayor de los \u00e9xitos en su gesti\u00f3n a Luciano Rivas, quien contar\u00e1 con todo mi apoyo&#8221;, sostuvo Aravena.<\/p>\n\n\n\n<p>En la misma l\u00ednea, la parlamentaria a\u00f1adi\u00f3 que conf\u00eda en el profesionalismo y compromiso ciudadano de Luciano Rivas. \u201cNecesit\u00e1bamos una autoridad que no tema reconocer que hay terrorismo y exigir que se restablezca el Estado de Derecho, para que nuestra gente pueda volver a vivir en paz. Luciano conoce esta realidad de cerca como ex presidente de la Multigremial y ser\u00e1 un liderazgo potente antes las autoridades nacionales\u201d.<\/p>\n\n\n\n<p>Con un 58,21% de los votos emitidos por sobre el 41,79% que obtuvo su contrincante, Luciano Rivas asumir\u00e1 como primer gobernador regional electo en La Araucan\u00eda. A partir del 14 de julio, el nuevo gobernador regional asumir\u00e1 gran parte de las tareas que ejerce a la fecha el intendente de La Araucan\u00eda, como por ejemplo, ser el presidente del Consejo Regional, ejecutar planes de ordenamiento territorial y administrar los recursos regionales para las 32 comunas (Fondo Nacional de Desarrollo Regional), entre otras funciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_22451\" class=\"pvc_stats total_only  \" data-element-id=\"22451\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La parlamentaria esper\u00f3 los resultados y celebr\u00f3 el triunfo de Luciano Rivas en su comando, junto al candidato presidencial Sebasti\u00e1n<\/p>\n","protected":false},"author":1,"featured_media":22452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[3577,829],"class_list":["post-22451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-elecciones","tag-gobernador"],"a3_pvc":{"activated":true,"total_views":47,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/22451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=22451"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/22451\/revisions"}],"predecessor-version":[{"id":22453,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/22451\/revisions\/22453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/22452"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=22451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=22451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=22451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}