{"id":19282,"date":"2021-02-23T20:26:59","date_gmt":"2021-02-23T23:26:59","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=19282"},"modified":"2021-02-23T20:27:03","modified_gmt":"2021-02-23T23:27:03","slug":"rubro-gastronomico-califica-como-positivo-cierre-de-calle-bulnes-y-avenida-alemania-para-funcionar-durante-fase-2","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/02\/23\/rubro-gastronomico-califica-como-positivo-cierre-de-calle-bulnes-y-avenida-alemania-para-funcionar-durante-fase-2\/","title":{"rendered":"Rubro gastron\u00f3mico califica como positivo cierre de calle Bulnes y Avenida Alemania para funcionar durante fase 2"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_19282\" class=\"pvc_stats total_only  \" data-element-id=\"19282\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>A dos semanas de la decisi\u00f3n del cierre temporal al tr\u00e1nsito vehicular de las calles Bulnes y Avenida Alemania, para que los restaurantes establecidos puedan sacar sus mesas y atender en las veredas, los due\u00f1os de locales, gremio y autoridades calificaron como \u201cpositiva\u201d, la autorizaci\u00f3n emanada por la Seremi de Transportes junto a la Municipalidad de Temuco.<\/p>\n\n\n\n<p>As\u00ed lo manifest\u00f3 Ciro Figueroa, propietario y socio de locales Marriet, quien sostuvo que, \u201ctengo una evaluaci\u00f3n bastante buena y satisfactoria, porque como complemento a lo otorgado por la Municipalidad de sacar las mesas a la vereda, esta es una medida s\u00faper buena y que se ve con resultados r\u00e1pidos, como que la gente estaba esperando poder estar en un lugar as\u00ed, al aire libre. Independiente de la pandemia, la gente no estaba acostumbrada a poder disfrutar de sus espacios, entonces esto ha sido un complemento s\u00faper bueno para le gente, para disfrutar de las calles y para nosotros, como empresa gastron\u00f3mica, poder aumentar las ventas que nos ha permitido respirar un poco m\u00e1s tranquilos\u201d.<\/p>\n\n\n\n<p>Respecto a la eficacia de la medida referida a las ventas, Ciro Figueroa, afirm\u00f3 que, \u201cnosotros aumentamos m\u00e1s de un 100 por ciento respecto a lo que ven\u00edamos vendiendo antes, vend\u00edamos un 10 a 15 por ciento de lo que ten\u00edamos en tiempos normales y ahora nos estamos acercando mucho m\u00e1s sobre el 50 o 60 por ciento de una venta normal. Esperamos a que la gente pueda venir a disfrutar de lo que tenemos todos los locatarios ac\u00e1, lo hacemos con mucho cari\u00f1o y esfuerzo, nos hemos preocupado de las medidas que nos piden para poder evitar los contagios y tambi\u00e9n le pedimos la colaboraci\u00f3n a las personas para que nos ayuden para poder seguir con las medidas exigidas por la autoridad sanitaria\u201d.<\/p>\n\n\n\n<p>El alcalde de Temuco, Jaime Salinas, tambi\u00e9n visit\u00f3 a los locatarios y coment\u00f3 que, \u201cestamos muy contentos de poder estar aqu\u00ed, compartiendo y viendo c\u00f3mo se le ha dado un uso correcto a las medidas tomadas, as\u00ed que quiero agradecer tambi\u00e9n, no solo aqu\u00ed en Bulnes, sino que tambi\u00e9n en la Avenida Alemania, as\u00ed que agradecemos a la locomoci\u00f3n colectiva que tambi\u00e9n han tenido la paciencia de ayudar a los comerciantes, en este caso del rubro gastron\u00f3mico. Estamos trabajando en conjunto con la Seremi de Transportes y con el comercio establecido, por lo tanto, esta es una medida que ha tenido una evaluaci\u00f3n muy positiva y estamos reactivando la econom\u00eda local\u201d.<\/p>\n\n\n\n<p>Mientras que el presidente de la C\u00e1mara de Comercio de Temuco, Gustavo Valenzuela, dijo que, \u201cestamos muy agradecidos, tanto del alcalde como de la seremi de Transportes, quienes han hecho todo el esfuerzo y nos han escuchado a los comerciantes de Avenida Alemania y a la C\u00e1mara de Comercio, que tienen algo que decir, por eso los comerciantes cuando se unen y hacen propuestas son justamente para mejorar la alica\u00edda econom\u00eda de nuestra comuna y regi\u00f3n, porque estos ejemplos que hoy damos en la ciudad de Temuco, se pueden replicar en otras comunas de nuestra regi\u00f3n que han sido tan afectadas\u201d.&nbsp;<\/p>\n\n\n\n<p>La seremi de Transporte, Claudina Uribe, tambi\u00e9n se refiri\u00f3 a esta medida y sostuvo que, \u201ccomo equipo de la seremi de Transportes y Telecomunicaciones, estamos bien contentos de poder haber hecho un aporte y un granito de arena al llamado de este gremio, en conjunto con el alcalde de Temuco, en donde podemos comprobar que de repente son peque\u00f1as acciones, desde el punto de vista de la administraci\u00f3n p\u00fablica, que pueden generar impacto, entonces estamos muy contentos y evaluando permanentemente el impacto que esto tiene sobre el tr\u00e1nsito, y tambi\u00e9n muy agradecidos de la colaboraci\u00f3n de los operadores de transportes, porque tambi\u00e9n est\u00e1n haciendo su aporte y su apuesta con el gremio gastron\u00f3mico en donde finalmente estamos todos colaborando y empatizando con la causa que es salvar empleos\u201d.<\/p>\n\n\n\n<p>Sobre la extensi\u00f3n de esta medida, Claudina Uribe dijo que, \u201ctenemos como fecha por resoluci\u00f3n autorizada hasta el 27 de febrero, es la fecha que desde el punto de vista de la autorizaci\u00f3n de la seremi de Transporte ha fijado y son temas que tenemos que ir evaluando de cara a lo que va a ir sucediendo con el inicio de clases y temas que intervienen en el tr\u00e1nsito y flujo vehicular de la ciudad\u201d.<\/p>\n\n\n\n<p>Destacar adem\u00e1s que la medida solicitada por el municipio, va en apoyo del golpeado rubro gastron\u00f3mico y busca colaborar con la reactivaci\u00f3n econ\u00f3mica, la que se lleva a cabo gracias al avance de la comuna de Temuco al Paso 2 del Plan Paso a Paso, donde los comerciantes, luego de casi un a\u00f1o, ven cifras azules en sus ventas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/Calle-Bulnes3-1024x683.jpg\" alt=\"\" class=\"wp-image-19284\" srcset=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/Calle-Bulnes3-1024x683.jpg 1024w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/Calle-Bulnes3-768x512.jpg 768w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/Calle-Bulnes3.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_19282\" class=\"pvc_stats total_only  \" data-element-id=\"19282\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>A dos semanas de la decisi\u00f3n del cierre temporal al tr\u00e1nsito vehicular de las calles Bulnes y Avenida Alemania, para<\/p>\n","protected":false},"author":1,"featured_media":19283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[3554,462,395,3555],"class_list":["post-19282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-araucania","tag-bulnes","tag-calle","tag-gastronomia","tag-rubro"],"a3_pvc":{"activated":true,"total_views":61,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/19282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=19282"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/19282\/revisions"}],"predecessor-version":[{"id":19285,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/19282\/revisions\/19285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/19283"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=19282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=19282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=19282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}