{"id":19234,"date":"2021-02-22T15:55:07","date_gmt":"2021-02-22T18:55:07","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=19234"},"modified":"2021-02-22T15:55:09","modified_gmt":"2021-02-22T18:55:09","slug":"diputado-rathgeb-por-hechos-en-la-araucania-reitera-el-llamado-a-que-el-consejo-de-seguridad-nacional-sesione-en-la-region","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/02\/22\/diputado-rathgeb-por-hechos-en-la-araucania-reitera-el-llamado-a-que-el-consejo-de-seguridad-nacional-sesione-en-la-region\/","title":{"rendered":"Diputado Rathgeb por hechos en La Araucan\u00eda reitera el llamado a que el Consejo de Seguridad Nacional sesione en la Regi\u00f3n"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_19234\" class=\"pvc_stats total_only  \" data-element-id=\"19234\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p><strong>El parlamentario indic\u00f3 que ya es hora que las autoridades del nivel central lleguen a la zona para encabezar esta instancia y tomar decisiones ahora, o caso contrario la violencia podr\u00eda desembocar en escenarios a\u00fan peores donde vidas humanas se pongan en riesgo y la seguridad alimentaria.<\/strong><\/p>\n\n\n\n<p>D\u00edas complejos en materia de ataques incendiarios y tomas de predios particulares, se han vivido en La Araucan\u00eda en las \u00faltimas jornadas, raz\u00f3n por la cual el diputado de Renovaci\u00f3n Nacional por la zona, Jorge Rathgeb Schifferli, insisti\u00f3 en el llamado al Gobierno para que se hagan presentes en la zona y se convoque al Consejo de Seguridad Nacional.<\/p>\n\n\n\n<p>El congresista puntualiz\u00f3 que es ahora el momento para que el organismo sesione en la Regi\u00f3n y no a distancia, para de una forma encontrar soluciones entre todos los actores insertos en el conflicto, antes que la situaci\u00f3n pueda pasar a mayores y se ponga en riesgo la vida de las personas, o est\u00e9 en juego la seguridad alimentaria de la comunidad.<\/p>\n\n\n\n<p>Rathgeb emplaz\u00f3 al Ejecutivo a no demorar en la toma de decisiones y que estas lleguen ahora, para que no se repitan las escenas que se han visto durante los \u00faltimos d\u00edas en Lautaro y otras comunas de la Regi\u00f3n, donde se produjeron peleas entre particulares, se incendiaron viviendas y due\u00f1os de predios vieron vulnerada su seguridad.<\/p>\n\n\n\n<p>\u201cLa situaci\u00f3n en La Araucan\u00eda ha llegado a l\u00edmites inaceptables. El Presidente debe convocar a todos los ministerios y servicios relacionados en la Regi\u00f3n a fin de abocarse a este tema y como lo se\u00f1al\u00e9 hace casi dos semanas atr\u00e1s debe convocar al Consejo de Seguridad Nacional donde deben concurrir las m\u00e1ximas autoridades de los poderes del Estado con el objetivo de ver y analizar la situaci\u00f3n que se vive en la Regi\u00f3n. Hoy se est\u00e1 poniendo en riesgo la seguridad alimentaria de todo el pa\u00eds, por cuanto una Regi\u00f3n productora de alimentos como la nuestra, nadie va a querer invertir, nadie querr\u00e1 cosechar o prestar servicios porque se pone en riesgo la producci\u00f3n en las distintas zonas. Se debe tomar una decisi\u00f3n oportuna porque se est\u00e1 poniendo en riesgo la seguridad p\u00fablica y alimentaria de un pa\u00eds\u201d, puntualiz\u00f3 el diputado Rathgeb.<\/p>\n\n\n\n<p>El parlamentario tambi\u00e9n indic\u00f3 que con el actual escenario, se han visto perjudicados peque\u00f1os y medianos agricultores, como tambi\u00e9n comunidades ind\u00edgenas que no han podido sacar adelante sus producciones.<\/p>\n\n\n\n<p>\u201cEn las ocupaciones ilegales se han visto perjudicados peque\u00f1os y medianos productores y tambi\u00e9n muchas comunidades ind\u00edgenas que no han podido sacar su producci\u00f3n o no han podido cosechar el trabajo que han tenido durante todo un a\u00f1o\u201d, agreg\u00f3 el parlamentario.<\/p>\n\n\n\n<p>El congresista agreg\u00f3 que el Gobierno est\u00e1 en el momento para reaccionar y que en caso de que no lo haga de manera r\u00e1pida, las consecuencias para La Araucan\u00eda pueden ser a\u00fan m\u00e1s dif\u00edciles, tomando en cuenta que es una de las regiones que presenta mayor rezago en el pa\u00eds y los hechos de violencia no hacen m\u00e1s que retroceder en lo avanzado.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_19234\" class=\"pvc_stats total_only  \" data-element-id=\"19234\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El parlamentario indic\u00f3 que ya es hora que las autoridades del nivel central lleguen a la zona para encabezar esta<\/p>\n","protected":false},"author":1,"featured_media":19235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[1235,154,457],"class_list":["post-19234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-atentados","tag-diputado","tag-lautaro"],"a3_pvc":{"activated":true,"total_views":25,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/19234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=19234"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/19234\/revisions"}],"predecessor-version":[{"id":19236,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/19234\/revisions\/19236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/19235"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=19234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=19234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=19234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}