{"id":18945,"date":"2021-02-12T08:23:36","date_gmt":"2021-02-12T11:23:36","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=18945"},"modified":"2021-02-12T08:23:38","modified_gmt":"2021-02-12T11:23:38","slug":"carta-abierta-desde-wallmapu-un-aporte-a-la-discusion-de-la-paridad-de-genero","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/02\/12\/carta-abierta-desde-wallmapu-un-aporte-a-la-discusion-de-la-paridad-de-genero\/","title":{"rendered":"Carta abierta desde Wallmapu: un aporte a la discusi\u00f3n de la paridad de g\u00e9nero"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_18945\" class=\"pvc_stats total_only  \" data-element-id=\"18945\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>Las aqu\u00ed firmantes somos mujeres y disidencias que hacemos parte de las Organizaciones Sociales y Territoriales del Wallmapu (OSTW), plataforma que se constituy\u00f3 en la Regi\u00f3n de La Araucan\u00eda con el horizonte de disputar la conformaci\u00f3n y dise\u00f1o de la convenci\u00f3n constitucional, articulando una serie de actores sociales que finalmente logramos inscribir dos listas para los distritos 22 y 23.<\/p>\n\n\n\n<p>Publicamos esta carta para compartir nuestros an\u00e1lisis y reflexiones respecto al recurso de reclamaci\u00f3n en contra de la Resoluci\u00f3n No O-27 interpuesto el 21 de enero del presente por los partidos pol\u00edticos Revoluci\u00f3n Democr\u00e1tica, Comunes, Convergencia Social, Federaci\u00f3n Regionalista Verde Social y Partido Comunista, el cual plantea reparos frente a la paridad de g\u00e9nero en la conformaci\u00f3n de listas para el proceso constituyente. En el documento se pone en entredicho 19 casos en los que se acept\u00f3 la inscripci\u00f3n de listas, indicando que no cumpl\u00edan con los criterios paritarios de entrada, entre estas se menciona la nuestra, correspondiente al Distrito 22 por estar constituida por dos mujeres y tres hombres.<\/p>\n\n\n\n<p>En relaci\u00f3n a esto, dejamos los siguientes antecedentes para situar tan importante discusi\u00f3n:<\/p>\n\n\n\n<p>Participaci\u00f3n de las mujeres en el proceso constituyente:&nbsp;Consideramos un profundo avance en la construcci\u00f3n de una sociedad m\u00e1s equitativa y justa, el contar con mecanismos que permitan desarrollar un proceso constituyente paritario, por cuanto, la paridad aporta en subsanar la subrepresentaci\u00f3n que tenemos las mujeres en la discusi\u00f3n p\u00fablica, pero m\u00e1s importante a\u00fan, marca un hito en la lucha del movimiento feminista y convierte a Chile en el primer pa\u00eds del mundo en tener una convenci\u00f3n constitucional paritaria.<\/p>\n\n\n\n<p>Sin embargo, este es solo un primer paso en la apertura de espacios pol\u00edticos y de poder para las mujeres pues sabemos que existen determinantes sociales y culturales que terminan dejando a las mujeres de clases acomodadas y de las grandes urbes en dichos puestos, distando de generar una democracia representativa.<\/p>\n\n\n\n<p>Visi\u00f3n de la paridad de g\u00e9nero:&nbsp;La paridad vista solo desde una perspectiva feminista liberal, en base a una visi\u00f3n esencialista de los sexos, sirve a l\u00f3gicas que reproducen estereotipos identitarios y una estructura social del binarismo cisg\u00e9nero, excluyendo a las disidencias sexuales pero tambi\u00e9n las claras diferencias de clase\/g\u00e9nero\/territorialidad entre las distintas expresiones de ser mujer.<\/p>\n\n\n\n<p>La paridad que nos interesa construir, tiene que ver con la calidad en la participaci\u00f3n pol\u00edtica de las mujeres y de todos los sectores subordinados de la sociedad, propiciando una verdadera transformaci\u00f3n y revoluci\u00f3n social e incluyendo nuestras diferencias, particularidades, historias y vivencias.<\/p>\n\n\n\n<p>Org\u00e1nica OSTW:&nbsp;Una de las listas cuestionadas por paridad de g\u00e9nero, es la lista del distrito 22 de las Organizaciones Sociales y Territoriales del Wallmapu. La OSTW ha desarrollado un proceso pol\u00edtico transformador y diametralmente distinto de la pol\u00edtica patriarcal tradicional. Desde su origen, esta plataforma ha tenido un especial cuidado por desarrollar un proceso profundamente democr\u00e1tico, horizontal, abierto, representativo y participativo, acordando de manera siempre colectiva, formas de tomar decisiones que fueran lo m\u00e1s justas posible, en el m\u00e9todo para decidir la configuraci\u00f3n de las listas, prelaci\u00f3n de las candidaturas, desarrollo program\u00e1tico, etc.<\/p>\n\n\n\n<p>Nuestro objetivo siempre fue que nuestras listas representaran los movimientos sociales de la regi\u00f3n y por eso es que en el Distrito 22 tenemos a las compa\u00f1eras Ximena Salgado y Alejandra Rivas, ambas activistas sociales y militantes de organizaciones feministas en sus respectivas comunas. Como<\/p>\n\n\n\n<p>Si la lista del distrito 22 no termin\u00f3 configurada por tres mujeres y tres hombres, no se debi\u00f3 a la falta de esfuerzos por alcanzar una representaci\u00f3n igualitaria de hombres, mujeres y diversidades sexuales, sino m\u00e1s bien a problemas estructurales desarrollados en otros puntos de esta carta. En este caso, creemos mucho m\u00e1s valioso el proceso que hemos desarrollado, que el balance de g\u00e9neros en la configuraci\u00f3n de las listas.<\/p>\n\n\n\n<p>Consideraci\u00f3n hacia las candidaturas cuestionadas:&nbsp;las organizaciones y mujeres que a nivel central desarrollaron estos cuestionamientos no manifestaron inter\u00e9s por comprender la realidad local de las candidaturas feministas y de organizaciones de disidencia sexual levantadas en el Distrito 22. Esto nos parece un error en el proceder, que reproduce las l\u00f3gicas jer\u00e1rquicas y patriarcales de la pol\u00edtica y de las relaciones sociales.<\/p>\n\n\n\n<p>La pol\u00edtica antipatriarcal debe ser en primer lugar situada, lo que implica reconocer los territorios y las actor\u00edas locales que viven y combaten diariamente las formas de subordinaci\u00f3n y la violenta desigualdad que nos segrega por g\u00e9nero, clase y raza. Para conseguir una verdadera transformaci\u00f3n social, tenemos que apostar por cambios sociales y culturales, lo cual supone cambios conductuales que disten de los mecanismos formales.<\/p>\n\n\n\n<p>Consideraciones contextuales y territoriales:&nbsp;es sabido que&nbsp;en los sectores m\u00e1s empobrecidos la participaci\u00f3n de las mujeres en la vida social y pol\u00edtica es m\u00e1s dif\u00edcil de ejercer, las candidaturas requieren una serie de condiciones para hacerse posibles, solvencia econ\u00f3mica, resguardo de espacios familiares y del hogar, entre otras. Esto cobra especial relevancia cuando consideramos que la regi\u00f3n de La Araucan\u00eda es la m\u00e1s empobrecida de Chile, aqu\u00ed existen profundas desigualdades territoriales en la manifestaci\u00f3n de la pobreza, las cuales est\u00e1n asociadas al ingreso econ\u00f3mico, a las caracter\u00edsticas f\u00edsicas y al entorno sociocultural de cada<\/p>\n\n\n\n<p>org\u00e1nica apostamos por construir una l\u00f3gica de conformaci\u00f3n de lista<\/p>\n\n\n\n<p>enfoc\u00e1ndonos en levantar candidaturas de mujeres l\u00edderes, representantes de sus colectivos y<\/p>\n\n\n\n<p>territorios, luchadoras sociales. Al mismo tiempo, pusimos dentro de los requisitos que cualquier<\/p>\n\n\n\n<p>persona que se presentara como candidata o candidato deb\u00eda tener un compromiso y trayectoria<\/p>\n\n\n\n<p>con la erradicaci\u00f3n de todas las violencias de g\u00e9nero.<\/p>\n\n\n\n<p>territorio. Este territorio se caracteriza por tener el mayor \u00edndice de pobreza multidimensional a nivel pa\u00eds, donde la mayor concentraci\u00f3n se localiza en la provincia de Malleco (Casen, 2017), que comprende las comunas del Distrito 22. Esto conlleva una clara feminizaci\u00f3n de la pobreza y, lamentablemente, sabemos que ser mujer pobre, no es lo mismo que ser hombre pobre. Esta situaci\u00f3n precaria impacta en la autonom\u00eda econ\u00f3mica y en la autonom\u00eda en la toma de decisiones, cuestiones que hacen altamente compleja la participaci\u00f3n de mujeres en espacios sociales y p\u00fablicos y m\u00e1s a\u00fan en espacios pol\u00edticos. Esta realidad tambi\u00e9n es la nuestra y la de nuestras org\u00e1nicas y queda de manifiesto en que, a pesar de grandes esfuerzos, no pudimos concretar una sexta candidatura mujer.<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es el feminismo que queremos construir?&nbsp;Finalmente, el objetivo de esta carta abierta es emplazar a construir un espacio de di\u00e1logo respecto a la calidad de la participaci\u00f3n pol\u00edtica, de feminismo y de luchas antipatriarcales que estamos construyendo. Desde nuestra parte, apostamos por un tipo de pr\u00e1ctica en que las jerarquizaciones de clase, de racializaci\u00f3n y etnicidad, y de sexo-genero se pongan en cuestionamiento permanente con el fin de erradicarlas. Pensamos que la nueva constituci\u00f3n debe situarse desde una perspectiva feminista, antipatriarcal, anticapitalista y antiextractivista.<\/p>\n\n\n\n<p>Invitamos a quienes han promovido la defensa de la paridad s\u00f3lo como una cuesti\u00f3n num\u00e9rica cuestionando nuestro proceso de constituci\u00f3n de lista sin conocerlo, a que conversemos, a que conozcan a las candidatas que ac\u00e1 se han levantado desde procesos de base, a las luchas cotidianas que llevamos como mujeres y disidencias en nuestros territorios.<\/p>\n\n\n\n<p>Firman: Mujeres y disidencias sexuales y de g\u00e9nero de las Organizaciones Sociales y territoriales del Wallmapu.<\/p>\n\n\n\n<p>Ximena Salgado Kuwahara, Colectiva feminista y de disidencias sexuales\/g\u00e9nero Llanca Newen, Agrupaci\u00f3n de ciudadanos y ciudadanas autoconvocados Constitucional Victoria. Candidata lista OSTW Distrito 22.<\/p>\n\n\n\n<p>Alejandra Rivas Troncoso, Asamblea Popular de Pur\u00e9n, Pur\u00e9n. Candidata D22 lista OSTW.<\/p>\n\n\n\n<p>Alejandra Parra Mu\u00f1oz, Red de Acci\u00f3n por los Derechos Ambientales, Red de Defensa de los Territorios, Temuco. Candidata de la lista OSTW Distrito 23.<\/p>\n\n\n\n<p>Loreto Lagos Sanhueza, Movimiento ambiental intercultural de la cuenca del Trancura MAI, Fundaci\u00f3n Ra\u00edces de Puc\u00f3n, Candidata D23 lista OSTW, Cuenca del Mallolafken, Puc\u00f3n.<\/p>\n\n\n\n<p>Ana Vera Haro, Asamblea Popular Paredes, Candidata Feminista y Popular, Lista OSTW, D23\/Temuco\/Wallmapu.<\/p>\n\n\n\n<p>Ximena Cuadra Montoya. Red de Acci\u00f3n por los Derechos Ambientales, Red de Defensa de los Territorios, Temuco.<\/p>\n\n\n\n<p>Javiera Baeza Merdanevic. Comando ciudadano El Pueblo Aprueba, Temuco; Coordinadora No+AFP Wallmapu.<\/p>\n\n\n\n<p>Ana Carolina Sandoval Dur\u00e1n. Colectiva feminista y de disidencias sexuales\/g\u00e9nero Llanca Newen. Victoria. Wallmapu<\/p>\n\n\n\n<p>Paola Castro Zambrano, Alcald\u00eda- Constituyente Temuko, Temuco.<\/p>\n\n\n\n<p>Alejandra Aillapan Huiriqueo, Candidata independiente a Alcald\u00eda Villarrica. Movimiento por una alcald\u00ed-a ciudadana para Villarrica, Villarrica.<\/p>\n\n\n\n<p>Francisca Melin Valenzuela, Asamblea Kimun cuidadano Victoria y ONG oveja verde, Victoria. Loreto Vidal Estay, Creando Mallolafken Villarrica, Villarrica.<br>Aurea Mu\u00f1oz Saldivia, Red de Defensa de los Territorios, Padre las Casas.<br>Isabel Saravia, Aguas libres Villarrica, Villarrica.<\/p>\n\n\n\n<p>Camila Reche Alvarez, Colectivo Feminista Kelluzomowen Likan-Ray, comuna de Villarrica. Paulina Morales, Corporaci\u00f3n Intercultural Frontera, Vilc\u00fan.<br>Silvia Sep\u00falveda Ojeda, Coordinadora NO m\u00e1s AFP Pitrufqu\u00e9n, comuna Pitrufquen.<\/p>\n\n\n\n<p>Jimena Sanhueza Molina, Movimiento Ambiental Intercultural de la Cuenca del Trancura MAI, Puc\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/distrito-22.jpg\" alt=\"\" class=\"wp-image-18947\" srcset=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/distrito-22.jpg 940w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/distrito-22-768x644.jpg 768w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_18945\" class=\"pvc_stats total_only  \" data-element-id=\"18945\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Las aqu\u00ed firmantes somos mujeres y disidencias que hacemos parte de las Organizaciones Sociales y Territoriales del Wallmapu (OSTW), plataforma<\/p>\n","protected":false},"author":1,"featured_media":18946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[860,3530,2288,3529],"class_list":["post-18945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-carta","tag-firmantes","tag-genero","tag-walmapu"],"a3_pvc":{"activated":true,"total_views":68,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/18945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=18945"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/18945\/revisions"}],"predecessor-version":[{"id":18948,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/18945\/revisions\/18948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/18946"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=18945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=18945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=18945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}