{"id":18844,"date":"2021-02-08T23:00:41","date_gmt":"2021-02-09T02:00:41","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=18844"},"modified":"2021-02-09T10:04:57","modified_gmt":"2021-02-09T13:04:57","slug":"desconocidos-incendian-dependencias-de-la-municipalidad-de-villarrica-reportan-personas-detenidas","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2021\/02\/08\/desconocidos-incendian-dependencias-de-la-municipalidad-de-villarrica-reportan-personas-detenidas\/","title":{"rendered":"Incendio afecta a dependencias del Municipio de Villarrica, 12 personas son detenidas"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_18844\" class=\"pvc_stats total_only  \" data-element-id=\"18844\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>El hombre de 26 a\u00f1os de edad, cuenta con un amplio prontuario policial.<\/p>\n\n\n\n<p>Siendo aproximadamente las 20 horas del lunes, varias personas se congregaron a trav\u00e9s de redes sociales en los alrededores de la Municipalidad para realizar diversas intervenciones culturales.<\/p>\n\n\n\n<p>Es en ese contexto, que dicha actividad se vio abruptamente interrumpida por un grupo aproximado de 20 sujetos que comenzaron a provocar desmanes arrojando piedras a la comisar\u00eda, instalaron barricadas incendiarias en el sector c\u00e9ntrico de la comuna y lanzaron objetos incendiarios hacia el recinto municipal, instante (cerca de las 22 horas) en que uno de los artefactos alcanz\u00f3 las dependencias de la DIDECO por una de sus ventanas, provocando un incendio en sus instalaciones, el que fue controlado por personal de bomberos.<\/p>\n\n\n\n<p>Tras estos antecedentes, Carabineros de la 7\u00aa Comisar\u00eda desarroll\u00f3 intensas diligencias, consistentes en patrullajes por la zona de los desmanes y la revisi\u00f3n de material audiovisual registrado por c\u00e1maras municipales, logrando detener a 11 personas en un principio.<\/p>\n\n\n\n<p>Luego, en el marco de dichas averiguaciones y a eso de las 22:20 horas, el personal de la SIP de la comisar\u00eda logr\u00f3 detener a un hombre de 26 a\u00f1os, oriundo de Vi\u00f1a del Mar y el que cuenta con un nutrido historial de antecedentes policiales tales como maltrato de obra a Carabineros, des\u00f3rdenes, lesiones leves, robo y porte de arma punzante, entre otros.<\/p>\n\n\n\n<p>Tras su detenci\u00f3n y la revisi\u00f3n del registro de las c\u00e1maras, se pudo situar al delincuente en los hechos y que este particip\u00f3 directamente en el incendio de las oficinas de la Direcci\u00f3n de Desarrollo Comunitario (DIDECO), c\u00f3mo tambi\u00e9n en la quema del Pabell\u00f3n Patrio ubicado en la Municipalidad de Villarrica.<\/p>\n\n\n\n<p>Los antecedentes fueron puestos en conocimiento al Ministerio P\u00fablico, quien a trav\u00e9s de la Fiscal\u00eda Local de Villarrica, dispuso que tanto este \u00faltimo como el resto de los antisociales, pasen a primer control de detenci\u00f3n el d\u00eda de hoy.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><video controls src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/Municipio-Villarrica4.mp4\"><\/video><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-large-font-size\"><\/p>\n<\/div><\/div>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Ffrancisco.carrasco.9275%2Fposts%2F10226166048598118&amp;width=500&amp;show_text=true&amp;height=645&amp;appId\" width=\"500\" height=\"645\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fvincedeejay.cl%2Fposts%2F10159278940664577&amp;width=500&amp;show_text=true&amp;height=1036&amp;appId\" width=\"500\" height=\"1036\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Finostroza.carlosr%2Fposts%2F10225208887786444&amp;width=500&amp;show_text=true&amp;height=609&amp;appId\" width=\"500\" height=\"609\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/326e80cb-9854-4a01-a0a3-022d4439c01d.jpg\" alt=\"\" class=\"wp-image-18869\" srcset=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/326e80cb-9854-4a01-a0a3-022d4439c01d.jpg 960w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/326e80cb-9854-4a01-a0a3-022d4439c01d-768x1024.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/fe50496d-06ef-4c4e-88bd-8c8c64e07978.jpg\" alt=\"\" class=\"wp-image-18870\" srcset=\"https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/fe50496d-06ef-4c4e-88bd-8c8c64e07978.jpg 960w, https:\/\/temucotelevision.cl\/web\/wp-content\/uploads\/2021\/02\/fe50496d-06ef-4c4e-88bd-8c8c64e07978-768x1024.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_18844\" class=\"pvc_stats total_only  \" data-element-id=\"18844\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El hombre de 26 a\u00f1os de edad, cuenta con un amplio prontuario policial. Siendo aproximadamente las 20 horas del lunes,<\/p>\n","protected":false},"author":1,"featured_media":18845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[3517,807,588],"class_list":["post-18844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-araucania","tag-departamento","tag-municipalidad","tag-transito"],"a3_pvc":{"activated":true,"total_views":29,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/18844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=18844"}],"version-history":[{"count":20,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/18844\/revisions"}],"predecessor-version":[{"id":18875,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/18844\/revisions\/18875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/18845"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=18844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=18844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=18844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}