{"id":17593,"date":"2020-12-24T22:39:44","date_gmt":"2020-12-25T01:39:44","guid":{"rendered":"https:\/\/temucotelevision.cl\/web\/?p=17593"},"modified":"2020-12-24T22:39:47","modified_gmt":"2020-12-25T01:39:47","slug":"mario-gonzalez-logra-el-doble-de-firmas-para-postularse-como-alcalde-independiente-por-padre-las-casas","status":"publish","type":"post","link":"https:\/\/temucotelevision.cl\/web\/2020\/12\/24\/mario-gonzalez-logra-el-doble-de-firmas-para-postularse-como-alcalde-independiente-por-padre-las-casas\/","title":{"rendered":"Mario Gonz\u00e1lez logra el doble de firmas para postularse como alcalde independiente por Padre Las Casas"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_17593\" class=\"pvc_stats total_only  \" data-element-id=\"17593\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p>A pesar de la cuarentena que afect\u00f3 a Padre Las Casas durante las \u00faltimas semanas, el candidato independiente\u00a0a alcalde por Padre Las Casas, Mario Gonz\u00e1lez, logr\u00f3 recolectar el doble de las firmas necesarias para su postulaci\u00f3n, las cuales fueron presentadas\u00a0oficialmente al Servel.<\/p>\n\n\n\n<p>Fue ayer en la ma\u00f1ana cuando el candidato lleg\u00f3 hasta las puertas del Servicio Electoral a presentar un total de 246 firmas que logr\u00f3 reunir el candidato en la notaria durante\u00a0un mes y donde fueron los ciudadanos los que, a pesar de la pandemia, se las arreglaron para acudir y pedir que \u00e9l sea el candidatos a alcalde por la comuna.<\/p>\n\n\n\n<p>El Servel exig\u00eda un total de 129 firmas y Mario Gonz\u00e1lez logr\u00f3 246, lo que es un n\u00famero importante considerando que la inscripci\u00f3n de las candidaturas es en enero del 2021.<\/p>\n\n\n\n<p>&#8220;En tiempos de pandemia hemos logrado reunir el doble de firmas para mi candidatura como independiente por Padre Las Casas. Las entregamos al Servel y se est\u00e1n revisando y luego de ello se podr\u00e1 inscribir la candidatura por Padre Las Casas. Esta es una candidatura independiente, sin padrinos pol\u00edticos, una candidatura ciudadana y de los vecinos de la comuna&#8221;, dijo.<\/p>\n\n\n\n<p>Asegur\u00f3 que hoy es el momento de generar liderazgo horizontales y por eso prefiri\u00f3 no participar con el apoyo de ning\u00fan partido pol\u00edtico.<\/p>\n\n\n\n<p>&#8220;Yo creo que es momento de aglutinar liderazgos horizontales, tengo la impresi\u00f3n que la situaci\u00f3n es tan complicada que se requiere liderazgos que no nos separen y queremos eso para Padre Las Casas&#8221;, dijo el ex seremi, quien por tercera vez se presenta de candidato.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_17593\" class=\"pvc_stats total_only  \" data-element-id=\"17593\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/temucotelevision.cl\/web\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>A pesar de la cuarentena que afect\u00f3 a Padre Las Casas durante las \u00faltimas semanas, el candidato independiente\u00a0a alcalde por<\/p>\n","protected":false},"author":1,"featured_media":17594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[84],"tags":[202,3372,3373,2471],"class_list":["post-17593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-alcalde","tag-firmas","tag-independiente","tag-postulacion"],"a3_pvc":{"activated":true,"total_views":33,"today_views":0},"_links":{"self":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/17593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/comments?post=17593"}],"version-history":[{"count":1,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/17593\/revisions"}],"predecessor-version":[{"id":17595,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/posts\/17593\/revisions\/17595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media\/17594"}],"wp:attachment":[{"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/media?parent=17593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/categories?post=17593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temucotelevision.cl\/web\/wp-json\/wp\/v2\/tags?post=17593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}